﻿
{"id":33855,"date":"2016-11-28T17:00:08","date_gmt":"2016-11-28T16:00:08","guid":{"rendered":"http:\/\/www.betten.de\/magazin\/?p=33855"},"modified":"2024-12-20T14:38:31","modified_gmt":"2024-12-20T13:38:31","slug":"koerpergerechte-betten-worauf-achten","status":"publish","type":"post","link":"https:\/\/www.betten.at\/magazin\/koerpergerechte-betten-worauf-achten.html","title":{"rendered":"K\u00f6rpergerechte Betten: Worauf ist zu achten?"},"content":{"rendered":"<p><!-- INHALTSVERZEICHNIS-START --><\/p>\n<div id=\"inhaltsverzeichnis\">\n<div>Inhaltsverzeichnis:<\/div>\n<ol>\n<li><a href=\"#koerpertypen\">K\u00f6rpertypen<\/a>\n<ol>\n<li><a href=\"#o-typ\">O-Typ<\/a><\/li>\n<li><a href=\"#i-typ\">I-Typ \/ H-Typ \/ E-Typ<\/a><\/li>\n<li><a href=\"#x-typ\">X-Typ<\/a><\/li>\n<li><a href=\"#a-typ\">A-Typ<\/a><\/li>\n<li><a href=\"#v-typ\">V-Typ \/ Y-Typ<\/a><\/li>\n<\/ol>\n<\/li>\n<li><a href=\"#koerpergewicht\">K\u00f6rpergewicht<\/a><\/li>\n<li><a href=\"#koerperlaenge\">K\u00f6rperl\u00e4nge<\/a><\/li>\n<li><a href=\"#bettlaenge\">Wie lang sollte ein Bett sein?<\/a><\/li>\n<li><a href=\"#bettbreite\">Wie breit sollte ein Bett sein?<\/a><\/li>\n<li><a href=\"#betthoehe\">Wie hoch sollte ein Bett sein?<\/a><\/li>\n<li><a href=\"#koerpergerechte-matratzen\">K\u00f6rpergerechte Matratzen<\/a><\/li>\n<li><a href=\"#matratzenberatung\">Betten.at Matratzenberatung<\/a><\/li>\n<\/ol>\n<\/div>\n<p><a href=\"\/magazin\/wp-content\/uploads\/bett-koerpergerecht.jpg\" data-rel=\"lightbox-image-0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img decoding=\"async\" class=\"alignleft size-nexttonavi wp-image-33859\" src=\"\/magazin\/wp-content\/uploads\/bett-koerpergerecht.jpg\" alt=\"K\u00f6rpergerechte Betten: Worauf bei der Auswahl achten\" \/><\/a><br \/>\n<!-- INHALTSVERZEICHNIS-ENDE --><\/p>\n<div class=\"clearboth first-clearboth\"><\/div>\n<p>Damit wir entspannt liegen und erholsam schlafen k\u00f6nnen, ist die Wahl des richtigen Bettes elementar. Welches Bett und welche Komponenten der Bettausstattung dabei f\u00fcr uns passend sind, h\u00e4ngt von vielen Faktoren ab. Sehr wichtig ist, dass die Besonderheiten unseres K\u00f6rpers ber\u00fccksichtigt werden. Hier sind vor allem der K\u00f6rperbau, die K\u00f6rperl\u00e4nge und das K\u00f6rpergewicht von Bedeutung. Worauf Sie bei der Zusammenstellung eines k\u00f6rpergerechten Bettes f\u00fcr Ihre individuellen Anforderungen achten sollten, erfahren Sie in diesem Artikel.<\/p>\n<p><a name=\"koerpertypen\"><\/a><\/p>\n<h2>K\u00f6rpertypen<\/h2>\n<div id=\"attachment_33856\" style=\"width: 783px\" class=\"wp-caption aligncenter\"><a href=\"\/magazin\/wp-content\/uploads\/koerpertypen-bettenwahl.jpg\" data-rel=\"lightbox-image-1\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-33856\" class=\"wp-image-33856 size-full\" src=\"\/magazin\/wp-content\/uploads\/koerpertypen-bettenwahl.jpg\" alt=\"\u00dcberblick \u00fcber verschiedene K\u00f6rpertypen\" width=\"773\" height=\"621\" srcset=\"https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/koerpertypen-bettenwahl.jpg 773w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/koerpertypen-bettenwahl-150x121.jpg 150w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/koerpertypen-bettenwahl-300x241.jpg 300w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/koerpertypen-bettenwahl-768x617.jpg 768w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/koerpertypen-bettenwahl-441x354.jpg 441w\" sizes=\"auto, (max-width: 773px) 100vw, 773px\" \/><\/a><p id=\"caption-attachment-33856\" class=\"wp-caption-text\">\u00a9 stockvectorsstoker \u2013 Fotolia<\/p><\/div>\n<p>Die Einteilung in verschiedene K\u00f6rpertypen, die teilweise auch als Figurtypen bezeichnet werden, erfolgt anhand von anatomischen Merkmalen. Dabei gibt es unterschiedliche Arten der Kategorisierung. Sehr h\u00e4ufig ist von O-Typen, A-Typen, I-Typen\/H-Typen\/E-Typen, X-Typen und V-Typen\/Y-Typen die Rede, welche wir uns deshalb nachfolgend im Detail genauer anschauen wollen. \u00dcbrigens ist das Wissen um den eigenen K\u00f6rpertyp bzw. Figurtyp nicht nur hilfreich, wenn es um die Auswahl und Zusammenstellung des Bettes geht, sondern auch ein guter Anhaltspunkt f\u00fcr modische Entscheidungen<\/p>\n<p>Von Bedeutung beim K\u00f6rperbau sind bezogen auf die Bettausstattung insbesondere K\u00f6rperpartien, die st\u00e4rker ausgepr\u00e4gt sind. So machen eine breite H\u00fcfte oder breite Schultern eine h\u00f6here Nachgiebigkeit der Schlafunterlage erforderlich, die ein tieferes Einsinken der breiteren und damit automatisch auch schwereren K\u00f6rperzonen erm\u00f6glicht. K\u00f6rperpartien wie eine sehr schmale Taille hingegen, ben\u00f6tigen eine besondere Unterst\u00fctzung durch die Schlafunterlage, die in diesem Lagerungsbereich entsprechend fester ausfallen muss.<\/p>\n<p>\u00a0<\/p>\n<p><a name=\"o-typ\"><\/a><\/p>\n<h3>O-Typ<\/h3>\n<p><a href=\"\/magazin\/wp-content\/uploads\/o-typ.png\" data-rel=\"lightbox-image-2\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-33860 size-medium\" src=\"\/magazin\/wp-content\/uploads\/o-typ-300x257.png\" alt=\"Figurtypen \/ K\u00f6rpertypen: O-Typ\" width=\"300\" height=\"257\" srcset=\"https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/o-typ-300x257.png 300w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/o-typ-150x129.png 150w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/o-typ.png 350w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Der O-Typ ist ein K\u00f6rpertyp, der auch als ovale Form, Bambus oder bei Frauen als Rubensfigur bezeichnet wird. Beim O-Figurtypus liegt der K\u00f6rperschwerpunkt in der Mitte. Bauch und H\u00fcften sind entsprechend beim O-Typ rundlich, weich und voll ausgepr\u00e4gt. Das Ges\u00e4\u00df ist hingegen meist wenig ausgepr\u00e4gt (flacher Po), eine Taille ist kaum bis gar nicht vorhanden. Die Extremit\u00e4ten (Unterarme, Handgelenke, Beine, Fesseln) fallen beim O-Typ in der Regel schlank aus. Frauen im O-Typ haben h\u00e4ufig eine sehr gro\u00dfe Oberweite.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><a name=\"uebergewicht-koerpertypen\"><\/a><\/p>\n<div class=\"infokasten\">\n<h3>\u00dcbergewicht und K\u00f6rpertypen<\/h3>\n<p style=\"clear: left;\">\u00dcbergewicht kann bei Frauen und M\u00e4nnern auftreten. Es gibt allerdings Unterschiede in der Art wie bzw. wo das Fett vom K\u00f6rper gespeichert wird:<\/p>\n<div class=\"clear\"><\/div>\n<p style=\"clear: left;\"><strong>Birne<\/strong><br \/>\nBei 85% der \u00fcbergewichtigen Frauen lagert sich das Fett in erster Linie an den H\u00fcften, am Ges\u00e4\u00df, an den Oberschenkeln und an den Armen ab. Durch derartige Fettanlagerungen ergibt sich eine typische Birnenform. In der medizinischen Fachsprache wird eine solche Fettverteilung als periphere Adipositas bezeichnet. Nur 20% der \u00fcbergewichtigen M\u00e4nner sind von einer peripheren Adipositas betroffen, welche gemeinhin als weniger gef\u00e4hrlich beurteilt wird, weil die Fettanlagerungen dabei schneller wieder abgebaut werden k\u00f6nnen.<\/p>\n<div class=\"clear\"><\/div>\n<p style=\"clear: left;\"><strong>Apfel<\/strong><br \/>\nBei 80% der \u00fcbergewichtigen M\u00e4nner wird das Fett vornehmlich im Bauchbereich gespeichert. Diese markante Fettanlagerung, die den K\u00f6rper apfelf\u00f6rmig erscheinen l\u00e4sst, wird umgangssprachlich auch gerne als Bierbauch bezeichnet. In der Medizin spricht man hier von der abdominalen Adipositas, welche nur bei 15% der \u00fcbergewichtigen Frauen feststellbar ist.<\/p>\n<p>Siehe hierzu auch: <a href=\"#thv\">Taille-H\u00fcft-Verh\u00e4ltnis (THV)<\/a><\/p>\n<\/div>\n<p><a name=\"a-typ\"><\/a><\/p>\n<h3>A-Typ<\/h3>\n<p><a href=\"\/magazin\/wp-content\/uploads\/a-typ.png\" data-rel=\"lightbox-image-3\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-33861\" src=\"\/magazin\/wp-content\/uploads\/a-typ-300x257.png\" alt=\"Figurtypen \/ K\u00f6rpertypen: A-Typ\" width=\"300\" height=\"257\" srcset=\"https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/a-typ-300x257.png 300w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/a-typ-150x129.png 150w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/a-typ.png 350w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Der A-Typ ist \u00fcberwiegend bei Frauen vorzufinden und nur selten bei M\u00e4nnern festzustellen. Man bezeichnet diesen Figurtyp auch als Birne oder Dreiecksform. Die H\u00fcften fallen beim A-Typen rund aus (\u201egeb\u00e4rfreudiges Becken\u201c). Sie sind breiter als der Brustbereich. Die Schultern sind beim A-Typen in der Regel schmaler als der restliche Oberk\u00f6rper. Die Taille ist oft schmal und ausgepr\u00e4gt. W\u00e4hrend der Bauch meist flach ausf\u00e4llt, sind der h\u00e4ufig Po rund und die Oberschenkel kr\u00e4ftig. Die Arme des A-Typen sind lang und d\u00fcnn.<\/p>\n<p>Da beim A-Typen die H\u00fcften breit und die Schultern schmal ausfallen, muss die Matratze bzw. Schlafunterlage bei diesem K\u00f6rpertyp besonders stark im H\u00fcftbereich nachgeben und so ein tieferes Einsinken des Beckens erlauben.<\/p>\n<p><a name=\"i-typ\"><\/a><\/p>\n<h3>I-Typ \/ H-Typ \/ E-Typ<\/h3>\n<p><a href=\"\/magazin\/wp-content\/uploads\/i-typ.png\" data-rel=\"lightbox-image-4\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-33862\" src=\"\/magazin\/wp-content\/uploads\/i-typ-300x257.png\" alt=\"Figurtypen \/ K\u00f6rpertypen: I-Typ\" width=\"300\" height=\"257\" srcset=\"https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/i-typ-300x257.png 300w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/i-typ-150x129.png 150w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/i-typ.png 350w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Kennzeichnend f\u00fcr den I-Typen sowie f\u00fcr den H-Typen ist eine sehr gerade K\u00f6rperform. Beide K\u00f6rpertypen zeichnen sich dadurch aus, dass Schulter, Brust und Taille in etwa ein identisches Ma\u00df aufweisen. Auch die H\u00fcfte ist beim I-Typen und H-Typen kaum ausgepr\u00e4gt, Bauch und Po sind meist flach und bei Frauen gibt es nur wenig Brust. Die Arme sind in der Regel lang und d\u00fcnn. Beide K\u00f6rpertypen lassen sich auch als Rechteckform definieren, wobei das Rechteck beim I-Typen schmaler ausf\u00e4llt als beim H-Typen.<\/p>\n<p>Der I-Typ ist von einer sehr schlanken Statur, h\u00e4ufig auch gro\u00df und sehr gut trainiert. F\u00fcr den linear gebauten I-Typen gibt es auch die Bezeichnungen R\u00f6hre oder Tulpe. Frauen im I-Typus sind oft von geringerer K\u00f6rpergr\u00f6\u00dfe und leichtgewichtig.<\/p>\n<p>Der H-Typ wird teilweise auch als Bananentyp bezeichnet. Die Figur des H-Typen wird auch als klassisch oder maskulin (gilt auch f\u00fcr Frauen mit diesem K\u00f6rpertyp) definiert. Er ist oft wie der H-Typ gr\u00f6\u00dfer gewachsen, wobei das K\u00f6rpergewicht im Vergleich h\u00f6her ausf\u00e4llt, so dass Personen dieses Figurtyps h\u00e4ufig schwerer sind. Da der Schulterbereich und die H\u00fcfte beide ausgepr\u00e4gt breit ausfallen, \u00fcbt der H-Typ deshalb sehr viel Druck auf seine Schlafunterlage aus, was bei der Zusammenstellung der Bettausstattung unbedingt ber\u00fccksichtigt werden muss.<\/p>\n<p>Sowohl beim I-Typen als auch beim H-Typen ist \u00fcblicherweise kein \u00dcbergewicht festzustellen.<\/p>\n<p>Gelegentlich liest man auch vom E-Typen, welcher vom Grundprinzip \u00e4hnlich wie der H-Typ gebaut ist. Auch der E-Typ ist gro\u00df gewachsen und bringt dementsprechend mehr Gewicht auf die Waage. Der Umfang von Schultern, Bauch und Becken weist beim E-Typen in etwa identische Ma\u00dfe auf. Das K\u00f6rpergewicht verteilt sich beim E-Typen relativ gleichm\u00e4\u00dfig.<\/p>\n<p><a name=\"x-typ\"><\/a><\/p>\n<h3>X-Typ<\/h3>\n<p><a href=\"\/magazin\/wp-content\/uploads\/x-typ.png\" data-rel=\"lightbox-image-5\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-33863\" src=\"\/magazin\/wp-content\/uploads\/x-typ-300x257.png\" alt=\"Figurtypen \/ K\u00f6rpertypen: X-Typ\" width=\"300\" height=\"257\" srcset=\"https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/x-typ-300x257.png 300w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/x-typ-150x129.png 150w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/x-typ.png 350w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>F\u00fcr den X-Typen gibt es auch die Bezeichnung Sanduhr, was daher r\u00fchrt, dass bei diesem Figurtyp Schultern bzw. Brustbereich sowie die H\u00fcfte sehr ausgepr\u00e4gt sind, w\u00e4hrend die Taille auff\u00e4llig schmal ausf\u00e4llt. Auf diese Weise entsteht eine typische X-Form bzw. Sanduhr-Form. Der X-Typ weist beim Brust- sowie H\u00fcftumfang in etwa identische Ma\u00dfe auf. Er ist der klassische weibliche Figurtyp, wobei Po und Oberschenkel meist feminine Rundungen aufweisen. Eine weitere Bezeichnung f\u00fcr den X-Typen ist Wespe.<\/p>\n<p>Die sehr schmal ausfallende Taille des X-Typen macht eine Schlafunterlage erforderlich, die die Taille optimal (unter-)st\u00fctzt.<\/p>\n<p><a name=\"v-typ\"><\/a><\/p>\n<h3>V-Typ \/ Y-Typ<\/h3>\n<p><a href=\"\/magazin\/wp-content\/uploads\/v-typ.png\" data-rel=\"lightbox-image-6\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-33864 size-medium\" src=\"\/magazin\/wp-content\/uploads\/v-typ-300x257.png\" alt=\"Figurtypen \/ K\u00f6rpertypen: V-Typ\" width=\"300\" height=\"257\" srcset=\"https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/v-typ-300x257.png 300w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/v-typ-150x129.png 150w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/v-typ.png 350w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Statt vom V-Typen ist h\u00e4ufig auch vom Apfeltypen oder von einer umgedrehten Dreiecksform die Rede. Die Schulter- und Brustpartie ist beim V-Typen sehr stark ausgepr\u00e4gt. Taille und H\u00fcfte fallen hingegen beim V-Typen schmal aus. Frauen im V-Typus haben oft eine gro\u00dfe Oberweite. Die Beine des V-Typen sind h\u00e4ufig schlank mit festen Waden. Der V-Typ neigt zu Fettablagerungen am R\u00fccken, den Oberarmen, am Bauch und der Taille, wodurch der Oberk\u00f6rper noch st\u00e4rker an eine Apfelform erinnert. Das Ges\u00e4\u00df f\u00e4llt beim V-Typen meist klein und flach aus.<\/p>\n<p>\u00c4hnlich wie der V-Typ ist der Y-Typ, welcher sich bei M\u00e4nnern einer gro\u00dfen Beliebtheit erfreut, obwohl er nur verh\u00e4ltnism\u00e4\u00dfig selten festzustellen ist. Beim Y-Typ sind die Schultern und der R\u00fccken breit angelegt. Der Brustbereich des Y-Typen ist klar definiert. In Relation zu den Schultern fallen die H\u00fcften des Y-Typen eher schmal aus. Die Taille ist h\u00e4ufig kaum definiert.<\/p>\n<p>Die breiten Schultern des V-Typen bzw. Y-Typen erfordern eine Schlafunterlage, die eine ausgepr\u00e4gte Schulterentlastung bzw. ein tieferes Einsinken der Schulterpartie erm\u00f6glicht.<\/p>\n<p><a name=\"koerpergewicht\"><\/a><\/p>\n<h2>K\u00f6rpergewicht<\/h2>\n<p><a href=\"\/magazin\/wp-content\/uploads\/koerpergewicht-waage.png\" data-rel=\"lightbox-image-7\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-33865\" src=\"\/magazin\/wp-content\/uploads\/koerpergewicht-waage-300x270.png\" alt=\"Welche Rolle spielt das K\u00f6rpergewicht bei der Wahl von Bett und Matratze?\" width=\"300\" height=\"270\" srcset=\"https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/koerpergewicht-waage-300x270.png 300w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/koerpergewicht-waage-150x135.png 150w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/koerpergewicht-waage-441x398.png 441w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/koerpergewicht-waage.png 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Das K\u00f6rpergewicht spielt beim Bettenkauf eine sehr wichtige Rolle. Es sollte insbesondere bei der Wahl von Matratze und Unterfederung ber\u00fccksichtigt werden, da das Gewicht in Verbindung mit der Gewichtsverteilung \u00fcber den K\u00f6rper (siehe hierzu auch: K\u00f6rpertypen) die Anforderungen definiert, die an die Schlafunterlage gestellt werden.<\/p>\n<p>Zus\u00e4tzlich ist hierbei au\u00dferdem noch die bevorzugte Schlafposition miteinzubeziehen, weil der K\u00f6rper in Seitenlage anders als in R\u00fcckenlage unterst\u00fctzt sowie entlastet werden muss. So sollte die Wirbels\u00e4ule bei seitlicher Schlafposition mit einer geraden Linie vom Hals bis zum Stei\u00df durchzogen werden k\u00f6nnen. Wenn man auf dem R\u00fccken liegt, sollte die Wirbels\u00e4ule ihre nat\u00fcrliche Doppel-S-Form beibehalten k\u00f6nnen. Die Schlafunterlage muss in beiden F\u00e4llen an den korrekten Stellen nachgeben (einsinken erm\u00f6glichen) und in anderen Bereichen einen gewissen Widerstand leisten, um den K\u00f6rper dort zu unterst\u00fctzen und zu tragen. Das Schlafen auf dem Bauch soll an dieser Stelle nicht unber\u00fccksichtigt bleiben. Diese Schlafposition ist allerdings nur wenig empfehlenswert und konkret darauf abgestimmte L\u00f6sungen zur Bettausstattung kaum verf\u00fcgbar. Weitere Informationen zu den verschiedenen Schlafpositionen sowie zur richtigen Ausstattung der Schlafst\u00e4tte im Betten.at Magazin:<\/p>\n<ul>\n<li><a href=\"\/magazin\/schlafen-schlafpositionen-vorteile-nachteile.html\" target=\"_blank\" rel=\"noopener\">Die Schlafpositionen und ihre Vor- und Nachteile<\/a><\/li>\n<li><a href=\"\/magazin\/optimale-bettausstattung-schlafposition.html\" target=\"_blank\" rel=\"noopener\">Die optimale Bettausstattung f\u00fcr Ihre Schlafposition<\/a><\/li>\n<li><a href=\"\/magazin\/schlafen-schlafkomfort-matratzentypen.html\" target=\"_blank\" rel=\"noopener\">Matratzentypen \u2013 Matratzen f\u00fcr jede Schlafposition<\/a><\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<div class=\"infokasten\">\n<h3>Verschiedene Kennzahlen, Kategorien und Risikoklassifizierungen f\u00fcr das K\u00f6rpergewicht<br \/>\nbzw. die Bewertung von \u00dcbergewicht<\/h3>\n<p><img decoding=\"async\" style=\"width: 15%;\" src=\"\/magazin\/wp-content\/uploads\/piktogramm-information.png\" alt=\"icon-information\" \/><\/p>\n<p style=\"clear: left;\"><strong>Taillenumfang<\/strong><\/p>\n<p>\u00c4rzte haben schon Ende der 1940er Jahre eine Verbindung zwischen Fettanlagerungen am Bauch und Krankheitsbildern wie erh\u00f6htem Blutzucker, erh\u00f6hten Blutfettwerten oder Bluthochdruck festgestellt. Beim umgangssprachlichen \u201eH\u00fcftgold\u201c (Fettansammlungen an den H\u00fcften) war allerdings das Auftreten der genannten Erkrankungen nicht zu beobachten.<\/p>\n<p>Aus diesem Grund wird dem Umfang der Taille eine besondere Bedeutung beigemessen, wenn es um die Beurteilung von \u00dcbergewicht sowie um die Einsch\u00e4tzung des gesundheitlichen Risikos der \u00fcbersch\u00fcssigen Kilos geht.<\/p>\n<p>Bei Frauen zeigt ein Taillenumfang >80cm und bei M\u00e4nnern ein Taillenumfang >94cm ein m\u00e4\u00dfig erh\u00f6htes Risiko f\u00fcr das Auftreten der oben genannten Erkrankungen an. \u00dcbersteigt der Wert f\u00fcr den Taillenumfang bei Frauen 88 cm und bei M\u00e4nnern 102 cm ist das Krankheitsrisiko stark erh\u00f6ht.<\/p>\n<p>Die World Health Organisation WHO empfiehlt die Messung des Taillenumfangs zur Risikobewertung von \u00dcbergewicht.<\/p>\n<hr \/>\n<p><a name=\"thv\"><\/a><br \/>\n<strong>Taille-H\u00fcft-Verh\u00e4ltnis (THV) \/ waist-to-hip ratio (WHR)<\/strong><\/p>\n<p>Zu Beginn der 1980er Jahre hat sich weltweit die Bestimmung des Taille-H\u00fcft-Verh\u00e4ltnisses \u2013 kurz: THV \u2013 (international: waist-to-hip ration \u2013 kurz: WHR) zur Einteilung und Bewertung der K\u00f6rperfettverteilung durchgesetzt.<\/p>\n<p><em><strong>Wo wird gemessen?<\/strong><\/em><\/p>\n<p>Gemessen wird der Taillenumfang zwischen der Unterkante der untersten Rippe und dem Beckenkamm. Der Umfang der H\u00fcfte wird an der breitesten Stelle der H\u00fcften gemessen.<\/p>\n<p><em><strong>Die Formel zur Berechnung des Taille-H\u00fcft-Verh\u00e4ltnisses lautet:<\/strong><\/em><\/p>\n<p>THV = Umfang der Taille \/ Umfang der H\u00fcfte<\/p>\n<p>Bei Zugrundelegung dieser Formel spricht man bei einer Person &#8211; in Abh\u00e4ngigkeit von ihrem K\u00f6rper- bzw. Figurtypus \u2013 von \u00dcbergewicht, wenn folgende Werte berechnet werden:<\/p>\n<p>K\u00f6rpertyp Birnenform: < 0,85 Frauen | < 1,0 M\u00e4nner K\u00f6rpertyp Apfelform: > 0,85 Frauen | > 1,0 M\u00e4nner<\/p>\n<p>Siehe hierzu auch: <a href=\"#uebergewicht-koerpertypen\">\u00dcbergewicht und K\u00f6rpertypen<\/a><\/p>\n<p><em><strong>Kleines Rechenbeispiel:<\/strong><\/em><\/p>\n<p>Die oft propagierte Idealfigur von Frauen mit den Ma\u00dfen 90-60-90 zeichnet sich durch ein Taille-H\u00fcft-Verh\u00e4ltnis von 0,67 aus.<\/p>\n<hr \/>\n<p><strong>Body-Mass-Index (BMI)<\/strong><br \/>\n<a href=\"\/magazin\/wp-content\/uploads\/body-mass-index-normalgewicht-uebergewicht-untergewicht.jpg\" title=\"\" data-rel=\"lightbox-image-8\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"\/magazin\/wp-content\/uploads\/body-mass-index-normalgewicht-uebergewicht-untergewicht-300x213.jpg\" alt=\"Tabelle BMI - Body-Mass-Index\" width=\"300\" height=\"213\" class=\"size-medium wp-image-33857\" srcset=\"https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/body-mass-index-normalgewicht-uebergewicht-untergewicht-300x213.jpg 300w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/body-mass-index-normalgewicht-uebergewicht-untergewicht-150x107.jpg 150w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/body-mass-index-normalgewicht-uebergewicht-untergewicht-768x546.jpg 768w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/body-mass-index-normalgewicht-uebergewicht-untergewicht-441x314.jpg 441w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/body-mass-index-normalgewicht-uebergewicht-untergewicht.jpg 787w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Der mit BMI abgek\u00fcrzte Body-Mass-Index ist eine relativ bekannte und verbreitete Kennzahl, wenn es um die Bewertung des K\u00f6rpergewichts einer Person geht. Beim Body-Mass-Index wird das K\u00f6rpergewicht in Relation zum K\u00f6rpergewicht gesetzt.<\/p>\n<p><em><strong>Die Formel zur Berechnung des Body-Mass-Index lautet:<\/strong><\/em><\/p>\n<p>BMI = K\u00f6rpergewicht (in kg) : (K\u00f6rpergr\u00f6\u00dfe in m)\u00b2<\/p>\n<p><em><strong>Beispiel &#8211; Person mit 1,70 m K\u00f6rperl\u00e4nge und 65 kg K\u00f6rpergewicht:<\/strong><\/em><\/p>\n<p>65 : (1,70)\u00b2<br \/>\n65 : (1,70 x 1,70)<br \/>\n65 : 2,89 = 22,49<\/p>\n<p>BMI = 22,49<\/p>\n<p><em><strong>Was sagt der BMI aus?<\/strong><\/em><\/p>\n<p>BMI Werte \u2013 Mann:<\/p>\n<ul>\n<li>Untergewicht: unter 20<\/li>\n<li>Normalgewicht: 20-25<\/li>\n<li>\u00dcbergewicht: 26-30<\/li>\n<li>Fettleibigkeit: 31-40<\/li>\n<li>starke Fettleibigkeit: ab 40<\/li>\n<\/ul>\n<p>BMI-Werte \u2013 Frau:<\/p>\n<ul>\n<li>Untergewicht: unter 19<\/li>\n<li>Normalgewicht: 19-24<\/li>\n<li>\u00dcbergewicht: 25-30<\/li>\n<li>Fettleibigkeit: 31-40<\/li>\n<li>starke Fettleibigkeit: ab 40<\/li>\n<\/ul>\n<p><em><strong>Wichtige Hinweise zum Body-Mass-Index:<\/strong><\/em><\/p>\n<p>Obwohl bei der Berechnung des BMI zwar die beiden Parameter K\u00f6rpergr\u00f6\u00dfe und K\u00f6rpergewicht herangezogen werden, eignet sich der BMI nicht, um zu beurteilen, ob es sich bei einem h\u00f6heren K\u00f6rpergewicht um einen erh\u00f6hten Fettanteil (\u00dcbergewicht, Adipositas) oder um einen erh\u00f6hten Muskelanteil (wie z.B. bei einem Bodybuilder) handelt. Bei einem hohen BMI-Wert kann es sich entsprechend auch um eine \u00fcberdurchschnittlich muskul\u00f6se Person handeln, bei der hingegen der allgemeinen Definition von \u00dcbergewicht keine vermehrten Fettablagerungen vorhanden sind. Dementsprechend ist ein vom Normalgewicht abweichender BMI-Wert kein konkretes Indiz f\u00fcr Fettleibigkeit, da es sich auch um ein Plus an Muskelmasse handeln kann. Eine falsche Erh\u00f6hung des BMI-Wertes kann ebenfalls durch Krankheit bedingt sein, wenn z.B. schwergradige \u00d6deme (Wassereinlagerungen) vorliegen.<\/p>\n<p>Wenn die Extremit\u00e4ten nur schwach bemuskelt sind, f\u00fchrt dieses zu einem geringeren BMI. Eine Person mit einer derartig schwach ausgepr\u00e4gten Extremit\u00e4tenmuskulatur kann trotz eines BMI Wertes im normalgewichtigen Bereich \u00dcbergewicht bis hin zu Adipositas aufweisen.<\/p>\n<p>Es gibt auch kritische Meinungen zum Body-Mass-Index bzw. zu seiner Handhabung, wie Sie unter dem zweiten Link unserer weiterf\u00fchrenden Informationen zum BMI im Internet nachlesen k\u00f6nnen:<\/p>\n<p><a href=\"http:\/\/www.nutrisurvey.de\/info\/interaktives\/bmi.htm\" target=\"_blank\" rel=\"noopener\">http:\/\/www.nutrisurvey.de\/info\/interaktives\/bmi.htm<\/a><br \/>\n<a href=\"https:\/\/www.wissenschaft.de\/erde-umwelt\/rund-und-trotzdem-gesund-body-mass-index-wird-zu-streng-gehandhabt\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.wissenschaft.de\/erde-umwelt\/rund-und-trotzdem-gesund-body-mass-index-wird-zu-streng-gehandhabt\/<\/a><\/p>\n<div class=\"clearboth\"><\/div>\n<\/div>\n<p><strong>Rolle des K\u00f6rpergewichts bei der Wahl von Bett und Bettausstattung<\/strong><\/p>\n<p>Wie bereits erw\u00e4hnt, geh\u00f6rt das K\u00f6rpergewicht zu den wichtigen Faktoren, wenn es um die Auswahl von Matratze und Unterfederung bzw. Lattenrost geht. Dar\u00fcber hinaus sollte bei einem h\u00f6heren K\u00f6rpergewicht auch besonderes Augenmerk auf die Stabilit\u00e4t der Bettrahmenkonstruktion gelegt werden. Diese sollte aus robusten Materialien bestehen, die so miteinander verbunden sind, dass sie auch h\u00f6chsten Belastungen problemlos standhalten. Bei Doppelbetten empfiehlt sich die Entscheidung f\u00fcr ein Modell, welches einen Mittelholm zur durchg\u00e4ngigen Lattenrostauflage bietet, da dieses deutlich stabiler als eine punktuelle Auflage des Lattenrostes an wenigen Stellen ist.<\/p>\n<p>Bei den Matratzen gibt es viele verschiedene Arten wie Federkernmatratzen (mit Bonell- oder (Tonnen-)Taschenfederkern), Latexmatratzen, Kaltschaummatratzen oder Viscoschaummatratzen. Allen Matratzenarten ist gemein, dass eine Einteilung nach H\u00e4rtegraden erfolgt. Diese H\u00e4rtegrade, welche mit \u201eH\u201c in Verbindung mit einer Zahl (1-5) gekennzeichnet werden, geben nicht konkret wieder, wie fest eine Matratze ist, sondern beziehen sich auf die Eignung f\u00fcr ein bestimmtes K\u00f6rpergewicht. Generell gilt hier, je h\u00f6her das K\u00f6rpergewicht je h\u00f6her muss der H\u00e4rtegrad einer Matratze sein.<\/p>\n<p>Mit dem Matratzen-H\u00e4rtegrad gibt es allerdings ein gro\u00dfes Problem, welches darin besteht, dass dieser nicht genormt ist. Dementsprechend steht keine verbindliche Norm zur Verf\u00fcgung, die die genaue Eignung einer H1-, H2-, H3-, H4- oder H5-Matratze definiert. Jeder Hersteller legt hier eigene Richtlinien zugrunde, was eine Vergleichbarkeit erschwert bzw. unm\u00f6glich macht.<\/p>\n<p><strong>Trotz der fehlenden H\u00e4rtegradnormung f\u00fcr Matratzen sind h\u00e4ufig pauschalisierte Angaben zur Gewichtseignung der verschiedenen H\u00e4rtegrade zu finden:<\/strong><\/p>\n<ul>\n<li>H\u00e4rtegrad 1 \u2013 H1: weich (soft, sehr weich), bis 60 kg<\/li>\n<li>H\u00e4rtegrad 2 \u2013 H2: mittel (medium, weich), bis 80 kg bzw. 85 kg<\/li>\n<li>H\u00e4rtegrad 3 \u2013 H3: hart (fest), \u00fcber 80 kg bzw. 85 kg<\/li>\n<li>H\u00e4rtegrad 4 \u2013 H4: fest (sehr fest), ab 100 kg bis 130 kg<\/li>\n<li>H\u00e4rtegrad 5 \u2013 H5: sehr fest (extrem fest), ab 130 kg<\/li>\n<\/ul>\n<p><strong>Dar\u00fcber hinaus gibt es eine Richtwerttabelle zur H\u00e4rtegradwahl bei Matratzen, die neben dem K\u00f6rpergewicht auch die K\u00f6rpergr\u00f6\u00dfe ber\u00fccksichtigt, da sie sich am BMI orientiert:<\/strong><\/p>\n<div id=\"attachment_33858\" style=\"width: 1110px\" class=\"wp-caption aligncenter\"><a href=\"\/magazin\/wp-content\/uploads\/bmi-und-haertegrad.png\" data-rel=\"lightbox-image-9\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-33858\" class=\"size-full wp-image-33858\" src=\"\/magazin\/wp-content\/uploads\/bmi-und-haertegrad.png\" alt=\"Tabelle: Body-Mass-Index zur Auswahl des H\u00e4rtegrades bei Matratzen\" width=\"1100\" height=\"496\" srcset=\"https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/bmi-und-haertegrad.png 1100w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/bmi-und-haertegrad-150x68.png 150w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/bmi-und-haertegrad-300x135.png 300w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/bmi-und-haertegrad-768x346.png 768w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/bmi-und-haertegrad-1024x462.png 1024w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/bmi-und-haertegrad-441x199.png 441w\" sizes=\"auto, (max-width: 1100px) 100vw, 1100px\" \/><\/a><p id=\"caption-attachment-33858\" class=\"wp-caption-text\">Body-Mass-Index als Richtwert zur Auswahl des H\u00e4rtegrades bei Matratzen<\/p><\/div>\n<p>Grunds\u00e4tzlich ist der Ansatz bei der H\u00e4rtegradwahl nicht nur das K\u00f6rpergewicht zu ber\u00fccksichtigen, sondern auch die K\u00f6rperl\u00e4nge einzubeziehen, sinnvoll. Verteilt sich zum Beispiel ein K\u00f6rpergewicht bei einer Frau nur auf eine K\u00f6rperl\u00e4nge von 1,45 m wird diese in der Regel einen h\u00f6heren H\u00e4rtegrad als eine Frau mit einer K\u00f6rperl\u00e4nge von 1,75 m und einem identischen K\u00f6rpergewicht von 60 kg ben\u00f6tigen. Die punktuelle Belastung pro cm\u00b2 kann also bei identischem K\u00f6rpergewicht und stark abweichender K\u00f6rperl\u00e4nge wesentlich anders ausfallen, was ber\u00fccksichtigt werden muss, wenn es um die Auswahl einer optimalen Matratze geht.<\/p>\n<p>Dennoch eignet sich diese Tabelle nur bedingt als Entscheidungshilfe f\u00fcr die Bestimmung des notwendigen bzw. optimalen H\u00e4rtegrades einer Matratze, weil z.B. die H\u00e4rtegrade &#8211; wie erw\u00e4hnt &#8211; hersteller- und produktabh\u00e4ngig sehr unterschiedlich festgelegt sind. Im Betten.at Online-Shop finden Sie deshalb stets bei allen Matratzen neben einer von uns aufgrund einheitlicher eigener Ma\u00dfst\u00e4be definierten Gewichtsempfehlung f\u00fcr die H\u00e4rtegrade auch immer weiterf\u00fchrende Informationen beispielsweise zur wahrgenommenen Festigkeit der Matratze sowie zu ihrer Eignung f\u00fcr die verschiedenen Schlafpositionen. Au\u00dferdem bieten wir einen umfangreichen Fragebogen zur Modellauswahl bei unseren Matratzen an, der verschiedenste Parameter ber\u00fccksichtigt. (siehe hierzu auch: <a href=\"\/produktfinder\/matratzenberatung\" target=\"_blank\" rel=\"noopener\">Betten.at Matratzenberatung<\/a>). Wenn Sie mehr \u00fcber den Matratzen-H\u00e4rtegrad erfahren wollen, empfehlen wir Ihnen unseren Artikel: <a href=\"\/magazin\/matratze-welcher-haertegrad.html\" target=\"_blank\" rel=\"noopener\">Wie finde ich die passende Matratze f\u00fcr mein K\u00f6rpergewicht \u2013 welcher H\u00e4rtegrad passt zu mir?<\/a> im Betten.at Magazin.<\/p>\n<p>Der H\u00e4rtegrad ist \u00fcbrigens nicht nur f\u00fcr die Auswahl einer Matratze relevant, sondern ebenfalls von Bedeutung, wenn Sie sich f\u00fcr ein Boxspringbett interessieren. Bei Boxspringbetten wird der H\u00e4rtegrad in der Regel durch die auf der Federkern-Box aufliegenden Matratze definiert. Modellabh\u00e4ngig kann der H\u00e4rtegrad sich auch durch die Kombination einer bestimmten Boxen-Ausf\u00fchrung mit der Matratze ergeben. Auch die H\u00e4rtegrade bei Boxspringbetten sind nicht einheitlich genormt, so dass es auch hier sehr gro\u00dfe Unterschiede in Abh\u00e4ngigkeit von Hersteller und Modell gibt. Im Betten.at Online-Shop legen wir zur Definition der H\u00e4rtegrade der Boxspringbetten unseres Sortimentes einen einheitlichen Ma\u00dfstab zugrunde, \u00fcber den wir auch die jeweiligen Gewichtsempfehlungen definieren. Zus\u00e4tzlich gibt es f\u00fcr jedes unserer hochwertigen Schlafsysteme eine Vielzahl an weiterf\u00fchrenden Informationen zur Entscheidungsfindung, die unter anderem verschiedene Schlafpositionen miteinbeziehen.<\/p>\n<p>Der Lattenrost bzw. die Unterfederung sollte zun\u00e4chst zur gew\u00e4hlten Matratzenart passen. Bei einem h\u00f6heren K\u00f6rpergewicht sollte die Wahl auf ein Modell in XXL-Ausf\u00fchrung fallen, da diese nicht nur wesentlich stabiler konstruiert sind, sondern noch einmal die besonderen Anforderungen, die eine schwerere Person an die Schlafunterlage stellt, ber\u00fccksichtigt. Daraus ergibt sich im Zusammenspiel mit einer geeigneten Matratze eine optimale und ergonomische Liegest\u00e4tte, welche an den richtigen Stellen unterst\u00fctzt oder eben entsprechend nachgibt.<\/p>\n<p>Matratzen in einem hohen H\u00e4rtegrad sowie XXL-Lattenroste sollten nur von Personen verwendet werden, die ein entsprechend hohes K\u00f6rpergewicht auf die Waage bringen. Leichtere Personen werden auf derartigen Schlafunterlagen \u00e4hnlich wie auf einem Brett gelagert, da diese viel zu hart sind und kein Einsinken sowie keine K\u00f6rperanpassung mehr erlauben. Gleiches gilt auch im umgekehrten Fall: Bettet sich eine schwergewichtige Person auf einer Schlafunterlage, die auf die Bed\u00fcrfnisse einer leichteren Person zugeschnitten ist, ist dieses nicht nur ergonomisch sehr ung\u00fcnstig, sondern auch kaum zutr\u00e4glich f\u00fcr einen gesunden, erholsamen Schlaf. Die schwere Person w\u00fcrde viel zu weich liegen, was ein zu starkes Einsinken bzw. Durchh\u00e4ngen der K\u00f6rpermitte zur Folge hat. Der K\u00f6rper wird nicht gest\u00fctzt und die Wirbels\u00e4ule ger\u00e4t in eine unentspannte, unnat\u00fcrliche Form.<\/p>\n<p><a name=\"koerperlaenge\"><\/a><\/p>\n<h2>K\u00f6rperl\u00e4nge<\/h2>\n<p>Die L\u00e4nge des K\u00f6rpers bzw. die K\u00f6rpergr\u00f6\u00dfe ist unter anderem von Bedeutung, wenn es um die Bewertung des K\u00f6rpertypen oder um die Berechnung des Body-Mass-Index geht. Sehr wichtig ist au\u00dferdem die Einbeziehung der K\u00f6rperl\u00e4nge, wenn es um die Festlegung der Bettl\u00e4nge sowie um die Auswahl des passenden Bettdeckenformates geht.<\/p>\n<div class=\"infokasten\">\n<h3>Welches Format sollte die Bettdecke haben?<\/h3>\n<p style=\"clear: left;\"><a href=\"\/magazin\/wp-content\/uploads\/bettdecke-welches-format.jpg\" data-rel=\"lightbox-image-10\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-33866\" src=\"\/magazin\/wp-content\/uploads\/bettdecke-welches-format-300x200.jpg\" alt=\"Welche Formate gibt es bei Bettdecken? Welche Gr\u00f6\u00dfe ist optimal?\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/bettdecke-welches-format-300x200.jpg 300w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/bettdecke-welches-format-150x100.jpg 150w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/bettdecke-welches-format-768x513.jpg 768w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/bettdecke-welches-format-441x294.jpg 441w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/bettdecke-welches-format.jpg 848w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Bei den Bettdecken gibt es verschiedene Standardgr\u00f6\u00dfen, wobei 135 x 200 cm die Bettdeckengr\u00f6\u00dfe ist, die am h\u00e4ufigsten zu finden ist. Daneben gibt es Bettdecken in \u00dcberbreite (155 x 200 cm) und in Komfortgr\u00f6\u00dfe (155 x 220 cm). Bettdecken, die f\u00fcr Doppelbetten angeboten werden, haben im Standard ein Format von 200 x 200 cm und in Komfortgr\u00f6\u00dfe ein Format von 240 x 220 cm oder 260 x 240 cm.<\/p>\n<p>Allgemein sagt man, dass die Bettdecke etwa 50 cm breiter als die Matratze sein sollte. Daraus ergibt sich, dass die Standardgr\u00f6\u00dfe 135 x 200 cm f\u00fcr 80 cm sowie f\u00fcr 90 cm breite Betten eine gute Wahl ist. Bei einem Bett mit 100 cm Breite d\u00fcrfte es hingegen schon die \u00dcberbreite 155 x 200 cm sein.<\/p>\n<p>Die passende L\u00e4nge der Bettdecke orientiert sich an Ihrer K\u00f6rperl\u00e4nge. Hier gilt generell, dass die Decke ca. 20 cm l\u00e4nger als Ihr K\u00f6rper ausfallen sollte. Bettdecken in Standardl\u00e4nge empfehlen sich entsprechend f\u00fcr Personen bis ca. 1,80 m. Wer gr\u00f6\u00dfer ist, sollte \u00fcber die Anschaffung einer Bettdecke in \u00dcberl\u00e4nge nachdenken.<\/p>\n<p>Weitere Informationen im Betten.at Magazin: <a href=\"\/magazin\/schlafen-schlafkomfort-bettdecken.html\" target=\"_blank\" rel=\"noopener\">Einf\u00fchrung in die Welt der Bettdecken<\/a><\/p>\n<div class=\"clear\"><\/div>\n<\/div>\n<p><a name=\"bettlaenge\"><\/a><\/p>\n<h2>Wie lang sollte ein Bett sein?<\/h2>\n<p>F\u00fcr die Bettl\u00e4nge gilt generell, dass diese mindestens 15 cm (besser noch 20 cm) l\u00e4nger als der Nutzer des Bettes sein sollte. Die Standardl\u00e4nge von Betten betr\u00e4gt 200 cm. Hier sind entsprechend Personen mit einer K\u00f6rperl\u00e4nge bis etwa 1,85 m in der Regel gut aufgehoben. Ab einer K\u00f6rperl\u00e4nge von 1,85 m empfiehlt sich dementsprechend die Verwendung eines Bettes in \u00dcberl\u00e4nge. F\u00fcr die \u00dcberl\u00e4ngen gibt es zwei Standards bei Betten: 2,10 m und 2,20 m. Der Vollst\u00e4ndigkeit halber sei auch erw\u00e4hnt, dass Betten sowie Matratzen\/Lattenroste vereinzelt auch in der Unterl\u00e4nge 1,90 m angeboten werden.<\/p>\n<p>Ist das Bett zu kurz gew\u00e4hlt, kommt es automatisch zu einer gekauerten Schlafhaltung, die der erforderlichen Entspannung der Muskulatur entgegensteht und sich so nachhaltig negativ auf die Bandscheiben auswirken kann.<\/p>\n<p><a name=\"bettbreite\"><\/a><\/p>\n<h2>Wie breit sollte ein Bett sein?<\/h2>\n<p>Als Idealma\u00df f\u00fcr ein Einzelbett wird eine Bettbreite zwischen 90 cm und 100 cm angegeben. Daraus ergibt sich f\u00fcr Doppelbetten eine ideale Breite von 180 cm (2 x 90 cm) bzw. (2 x 100 cm). Sind die Platzverh\u00e4ltnisse eingeschr\u00e4nkt, kann auf die Einzelbettbreite 80 cm bzw. auf die Doppelbreite 160 cm (2 x 80 cm) ausgewichen werden. Von einer noch geringeren Breite ist abzuraten, weil dann kaum noch ausreichend Fl\u00e4che zur n\u00e4chtlichen Bewegung zur Verf\u00fcgung steht. Ein kleines Doppelbett mit 140 cm Breite ist daher meist lediglich f\u00fcr junge Leute noch gerade so hinnehmbar.<\/p>\n<p><a name=\"betthoehe\"><\/a><\/p>\n<h2>Wie hoch sollte ein Bett sein?<\/h2>\n<p>Die H\u00f6he des Bettes (oberer Abschluss der Liegefl\u00e4che) h\u00e4ngt mit der eigenen K\u00f6rperl\u00e4nge zusammen. Das Bett sollte so hoch sein, dass man beim seitlichen Sitzen auf der \u201eBettkante\u201c die F\u00fc\u00dfe auf dem Boden aufstellen kann. Wenn die F\u00fc\u00dfe in der Luft \u201ebaumeln\u201c, ist das Bett zu hoch. Sollten die Knie zu doll durchgedr\u00fcckt sein, ist das Bett zu niedrig. Beides ist nicht sinnvoll, da ein Hereinklettern und Herausspringen aus dem Bett ebenso unangenehm wie ein m\u00fchsames Hochk\u00e4mpfen aus zu niedriger Position ist.<\/p>\n<p>Ideal ist es, wenn sich das Becken oberhalb der Knie befindet, weil so ein leichteres Aufstehen m\u00f6glich ist. Es sollte jedoch zumindest so sein, dass sich Becken und Knie auf einer H\u00f6he befinden. Sind die Knie h\u00f6her als das Becken wird es schwerer mit dem Aufstehen.<\/p>\n<p>Um einen groben Anhaltspunkt zu haben, welche Betth\u00f6he f\u00fcr Sie passend ist, k\u00f6nnen Sie die Sitzh\u00f6he eines f\u00fcr Sie bequemen Stuhls oder Sofas messen. In der Regel liegt die optimale Betth\u00f6he zwischen 45 cm und 60 cm.<\/p>\n<p>Teilen sich zwei unterschiedlich gro\u00dfe Personen ein Doppelbett, sollte dieses in der H\u00f6he vorrangig auf die kleinere Person abgestimmt sein. Optimalerweise sucht man nach dem kleinsten gemeinsamen Nenner (gerade noch angenehm f\u00fcr die kleinere Person und ggf. gerade im Bereich der optimalen Einstiegsh\u00f6he f\u00fcr die gr\u00f6\u00dfere Person).<\/p>\n<p>Abgesehen davon, dass niedrige Betten wenig ergonomisch und komfortabel beim Ein- und Ausstieg sind, haben diese auch noch den Nachteil, dass die Luftumw\u00e4lzung hier schlechter von statten geht als bei hohen Modellen. Es kann zudem auch gesundheitlich belastend sein, wenn man zu dicht am Boden schl\u00e4ft (Staub, K\u00e4lte).<\/p>\n<p><a name=\"koerpergerechte-matratze\"><\/a><\/p>\n<h2>K\u00f6rpergerechte Matratze: Darauf kommt es an<\/h2>\n<p><a href=\"\/magazin\/wp-content\/uploads\/koerpergerechte-betten.jpg\" data-rel=\"lightbox-image-11\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-33867\" src=\"\/magazin\/wp-content\/uploads\/koerpergerechte-betten.jpg\" alt=\"Bei einer k\u00f6rpergerechten Matratze gibt die Matratze an den richtigen Stellen nach und unterst\u00fctzt den K\u00f6rper an anderen Stellen optimal.\" width=\"1600\" height=\"874\" srcset=\"https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/koerpergerechte-betten.jpg 1600w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/koerpergerechte-betten-150x82.jpg 150w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/koerpergerechte-betten-300x164.jpg 300w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/koerpergerechte-betten-768x420.jpg 768w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/koerpergerechte-betten-1024x559.jpg 1024w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/koerpergerechte-betten-441x241.jpg 441w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/a><\/p>\n<p>Damit eine Matratze k\u00f6rpergerecht ist, also die individuell variabel ausfallenden, spezifischen Anforderungen einer Person optimal erf\u00fcllt, spielen verschiedene Faktoren eine Rolle:<\/p>\n<ul>\n<li><strong>K\u00f6rpergewicht<\/strong> \u2192 Modellwahl \/ Wahl des H\u00e4rtegrades<\/li>\n<li><strong>Gr\u00f6\u00dfe \/ K\u00f6rperl\u00e4nge<\/strong> \u2192 Matratzenl\u00e4nge<\/li>\n<li><strong>K\u00f6rperbau \/ K\u00f6rpertyp<\/strong> \u2192 hier ist insbesondere das Verh\u00e4ltnis von Schulter-Taille-H\u00fcfte von Bedeutung \u2013 an welchen Stellen muss die Matratze besonders nachgeben und wo besonders st\u00fctzen<\/li>\n<li><strong>Bevorzugte Schlafposition<\/strong> \u2192 auf welche Anforderungen sollte die Matratze optimal zugeschnitten sein, um ergonomisches Einsinken zu erlauben (Punktbelastung Schulter und H\u00fcfte ist bei Seitenschl\u00e4fern wesentlich h\u00f6her als bei R\u00fcckenschl\u00e4fern)<\/li>\n<li><strong>Schmerzbereiche \/ k\u00f6rperliche Probleme<\/strong> \u2192 wo sollte der K\u00f6rper entlastet bzw. besonders durch die Matratze unterst\u00fctzt werden<\/li>\n<li><strong>Alter<\/strong> \u2192 generell wird hierzulande bevorzugt auf tendenziell harten Matratzen geschlafen \u2013 f\u00fcr junge Menschen ist dieses meist \u00fcberhaupt kein Problem, w\u00e4hrend \u00e4ltere Personen unbedingt auf eine druckfreie Lagerung von Wirbels\u00e4ule und Gelenken angewiesen sind und deshalb eine weichere Schlafunterlage ben\u00f6tigen.<\/li>\n<\/ul>\n<p>Die Matratzenart, die sich anhand des Kernmaterials definiert (z.B. Taschenfederkern oder Kaltschaum) spielt grunds\u00e4tzlich eine weniger gro\u00dfe Rolle. Eher nachteilig sind jedoch oft Bonell-Federkernmatratzen, da diese eine fl\u00e4chenelastische Wirkung aufweisen und sich aus diesem Grund beispielsweise bei Seitenlage oft nur unzureichend an die K\u00f6rperkonturen anpassen, wodurch in der Regel kaum eine ergonomische Lagerung des K\u00f6rpers erreicht wird.<\/p>\n<p>Daneben sind Matratzenart und Ausf\u00fchrung der Matratze von Bedeutung, wenn spezielle Anforderungen gestellt werden. Personen, die leichter frieren, ben\u00f6tigen eine Schlafunterlage, die mehr W\u00e4rme spendet. Wer zu vermehrtem Schwitzen neigt, sollte eine Matratze w\u00e4hlen, die sich durch einen guten Feuchtigkeitsabtransport und eine hohe Atmungsaktivit\u00e4t auszeichnet, was z.B. bei Kaltschaummatratzen der Fall ist. Allergiker brauchen beispielsweise eine Matratze mit waschbarem Bezug und ggf. mit einer besonderen textilen Ausr\u00fcstung, um die allergene Belastung so weit wie m\u00f6glich zu reduzieren.<\/p>\n<p>Eine k\u00f6rpergerechte Matratze tr\u00e4gt der Anatomie des Menschen Rechnung. Dieses wird durch eine Einteilung der Matratze in verschiedene Zonen erreicht. Besonders bew\u00e4hrt haben sich Matratzen mit einer Einteilung in f\u00fcnf oder sieben derartige Liegezonen. Die verschiedenen Zonen einer 5-Zonen- bzw. 7-Zonen-Matratze sind durch die Verwendung unterschiedlicher Materialien oder Einschnitte im Material verschieden weich oder fest ausgef\u00fchrt. So ist der Lagerungsbereich f\u00fcr die Schulter oder die H\u00fcfte weicher, damit diese schweren K\u00f6rperpartien besser in die Schlafunterlage einsinken k\u00f6nnen. Im Bereich des Kopfes oder der Taille ist die Matratze entsprechend fester ausgef\u00fchrt, um diese K\u00f6rperpartien zu st\u00fctzen und die Wirbels\u00e4ule so in einer entspannten Lage zu halten.<\/p>\n<p>F\u00fcr weitere Informationen empfehlen wir Ihnen die Lekt\u00fcre des Artikels: <a href=\"\/magazin\/matratze-kaufen-worauf-achten.html\" target=\"_blank\" rel=\"noopener\">Welche Matratze passt zu mir \u2013 Worauf muss ich beim Kauf einer Matratze achten?<\/a> im Betten.at Magazin.<\/p>\n<div class=\"infokasten\">\n<h3>Kopfkissen nicht vergessen!<\/h3>\n<p style=\"clear: left;\"><a href=\"\/magazin\/wp-content\/uploads\/nackenstuetzkissen.jpg\" data-rel=\"lightbox-image-12\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-33868\" src=\"\/magazin\/wp-content\/uploads\/nackenstuetzkissen-300x164.jpg\" alt=\"K\u00f6rpergerechtes Kissen nicht vergessen z.B. ein Nackenst\u00fctzkissen.\" width=\"300\" height=\"164\" srcset=\"https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/nackenstuetzkissen-300x164.jpg 300w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/nackenstuetzkissen-150x82.jpg 150w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/nackenstuetzkissen-768x419.jpg 768w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/nackenstuetzkissen-1024x559.jpg 1024w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/nackenstuetzkissen-441x241.jpg 441w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/nackenstuetzkissen.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Die empfindliche Halswirbels\u00e4ule wird von keiner Matratze optimal gest\u00fctzt. W\u00e4hlen Sie deshalb in Abh\u00e4ngigkeit von Ihrer bevorzugten Schlafposition sowie passend zu Ihren pers\u00f6nlichen Vorlieben ein Kopfkissen f\u00fcr Ihr Bett aus. Ob Sie dabei mit einem klassischen Federkissen oder mit einem speziellen Nackenst\u00fctzkissen besser liegen, l\u00e4sst sich pauschal nicht beantworten. Zu den Standardformaten bei den Kopfkissen geh\u00f6ren das quadratische Kissen in 80 x 80 cm sowie das rechteckige Kissen in 40 x 80 cm.<\/p>\n<p>Lesen Sie dazu mehr im Betten.at Magazin: <a href=\"\/magazin\/schlafen-schlafkomfort-kopfkissen.html\" target=\"_blank\" rel=\"noopener\">Das optimale Kopfkissen<\/a><\/p>\n<div class=\"clear\"><\/div>\n<\/div>\n<p><a name=\"matratzenberatung\"><\/a><\/p>\n<h2>Matratzenberatung: So einfach gelangen Sie im Betten.at Shop zur passenden Matratze<\/h2>\n<p>Um Ihnen den Weg zu einer optimal auf Ihre Bed\u00fcrfnisse abgestimmten Matratze zu erleichtern, stellen wir Ihnen im Betten.at Online-Shop einen Fragebogen zur Verf\u00fcgung, der f\u00fcr Sie automatisiert passende Matratzenmodelle ermittelt. In mehreren Schritten werden hierzu alle relevanten Parameter von der Wunschgr\u00f6\u00dfe \u00fcber Ihre k\u00f6rperlichen Merkmale und Schlafgewohnheiten bis hin zu Ihren pers\u00f6nlichen Liegew\u00fcnschen abgefragt. Im Anschluss erhalten Sie eine Auswahl geeigneter Modelle, die sich dann in Ruhe anschauen k\u00f6nnen.<\/p>\n<p><a href=\"\/produktfinder\/matratzenberatung\" target=\"_blank\" rel=\"noopener\">Klicken Sie hier, um direkt zum Matratzenfragebogen im Online-Shop zu gelangen<\/a><\/p>\n<p><strong>Exklusive Matratzenkollektion nach h\u00f6chsten ergonomischen Standards: youSleep<\/strong><\/p>\n<p><a href=\"\/magazin\/wp-content\/uploads\/yousleep-logo.jpg\" data-rel=\"lightbox-image-13\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-33869\" src=\"\/magazin\/wp-content\/uploads\/yousleep-logo.jpg\" alt=\"youSleep - Betten.at Marke f\u00fcr k\u00f6rpergerechtes Liegen und Schlafen\" width=\"220\" height=\"87\" srcset=\"https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/yousleep-logo.jpg 220w, https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/yousleep-logo-150x59.jpg 150w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/><\/a>Wenn Sie auf der Suche nach einer Kaltschaummatratze oder generell nicht auf ein bestimmtes Matratzenmaterial festgelegt sind, empfehlen wir Ihnen unser Sortiment an innovativen youSleep-Kaltschaummatratzen. Die youSleep Matratzen haben wir von Betten.at in enger Zusammenarbeit mit dem IGR (Institut f\u00fcr Gesundheit und Ergonomie GmbH) und dem Matratzenexperten Walter Braun entwickelt. Aktuell stehen verschiedene Ausf\u00fchrungen der hochwertigen Kaltschaummatratze zur Verf\u00fcgung, die jeweils auf unterschiedliche Anforderungen optimiert sind. <\/p>\n<p><strong>Pers\u00f6nliche Fachberatung am Telefon oder per Mail:<\/strong><\/p>\n<p>Gerne stehen wir Ihnen auch am Telefon oder per Mail f\u00fcr eine individuelle Beratung zur Matratzenwahl zur Verf\u00fcgung. Dabei beantworten wir Ihnen selbstverst\u00e4ndlich auch alle weiteren Fragen rund um die Zusammenstellung eines k\u00f6rpergerechten Bettes und geben Ihnen weitere Informationen zur Auswahl sowie konkrete Produktempfehlungen an die Hand.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>F\u00fcr einen erholsamen und entspannten Schlaf ist es besonders wichtig, das richtige Bett zu finden, welches zu einem passt. Besonders der individuelle K\u00f6rperbau spielt eine gro\u00dfe Rolle bei der Wahl von Bettgestell, Ausstattung und Co. In diesem Artikel erfahren Sie mehr zur Zusammenstellung eines k\u00f6rpergerechten Bettes.<\/p>\n","protected":false},"author":14,"featured_media":30517,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[414],"tags":[1744,1747],"class_list":["post-33855","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medizin-wissenschaft","tag-massivholzbetten","tag-polsterbetten"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>K\u00f6rpergerechte Betten: Worauf sollte ich achten? | Betten.at Magazin<\/title>\n<meta name=\"description\" content=\"Worauf kommt es bei einem k\u00f6rpergerechten Bett an? Infos zu den K\u00f6rpertypen sowie zur Auswahl der passenden Matratze und vieles mehr.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.betten.at\/magazin\/koerpergerechte-betten-worauf-achten.html\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"K\u00f6rpergerechte Betten: Worauf sollte ich achten? | Betten.at Magazin\" \/>\n<meta property=\"og:description\" content=\"Worauf kommt es bei einem k\u00f6rpergerechten Bett an? Infos zu den K\u00f6rpertypen sowie zur Auswahl der passenden Matratze und vieles mehr.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.betten.at\/magazin\/koerpergerechte-betten-worauf-achten.html\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-28T16:00:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-20T13:38:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/das-passende-bett-zu-meinem-koerper.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"435\" \/>\n\t<meta property=\"og:image:height\" content=\"245\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ulrich Carsten\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ulrich Carsten\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"27\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/koerpergerechte-betten-worauf-achten.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/koerpergerechte-betten-worauf-achten.html\"},\"author\":{\"name\":\"Ulrich Carsten\",\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#\\\/schema\\\/person\\\/7c1a4c0500ca2b101723693361b5750d\"},\"headline\":\"K\u00f6rpergerechte Betten: Worauf ist zu achten?\",\"datePublished\":\"2016-11-28T16:00:08+00:00\",\"dateModified\":\"2024-12-20T13:38:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/koerpergerechte-betten-worauf-achten.html\"},\"wordCount\":4646,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/koerpergerechte-betten-worauf-achten.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/wp-content\\\/uploads\\\/das-passende-bett-zu-meinem-koerper.jpg\",\"keywords\":[\"Massivholzbetten\",\"Polsterbetten\"],\"articleSection\":[\"Medizin &amp; Wissenschaft\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.betten.at\\\/magazin\\\/koerpergerechte-betten-worauf-achten.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/koerpergerechte-betten-worauf-achten.html\",\"url\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/koerpergerechte-betten-worauf-achten.html\",\"name\":\"K\u00f6rpergerechte Betten: Worauf sollte ich achten? | Betten.at Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/koerpergerechte-betten-worauf-achten.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/koerpergerechte-betten-worauf-achten.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/wp-content\\\/uploads\\\/das-passende-bett-zu-meinem-koerper.jpg\",\"datePublished\":\"2016-11-28T16:00:08+00:00\",\"dateModified\":\"2024-12-20T13:38:31+00:00\",\"description\":\"Worauf kommt es bei einem k\u00f6rpergerechten Bett an? Infos zu den K\u00f6rpertypen sowie zur Auswahl der passenden Matratze und vieles mehr.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/koerpergerechte-betten-worauf-achten.html#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.betten.at\\\/magazin\\\/koerpergerechte-betten-worauf-achten.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/koerpergerechte-betten-worauf-achten.html#primaryimage\",\"url\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/wp-content\\\/uploads\\\/das-passende-bett-zu-meinem-koerper.jpg\",\"contentUrl\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/wp-content\\\/uploads\\\/das-passende-bett-zu-meinem-koerper.jpg\",\"width\":435,\"height\":245},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/koerpergerechte-betten-worauf-achten.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.betten.at\\\/magazin\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"K\u00f6rpergerechte Betten: Worauf ist zu achten?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#organization\",\"name\":\"Betten.de\",\"url\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/wp-content\\\/uploads\\\/logo-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/wp-content\\\/uploads\\\/logo-1-1.jpg\",\"width\":500,\"height\":500,\"caption\":\"Betten.de\"},\"image\":{\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#\\\/schema\\\/person\\\/7c1a4c0500ca2b101723693361b5750d\",\"name\":\"Ulrich Carsten\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/wp-content\\\/uploads\\\/ucarsten-l-96x96.jpg\",\"url\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/wp-content\\\/uploads\\\/ucarsten-l-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/wp-content\\\/uploads\\\/ucarsten-l-96x96.jpg\",\"caption\":\"Ulrich Carsten\"},\"description\":\"Zertifizierter Bettenfachberater mit dem Schwerpunkt Matratzen in unserem Online-Shop Betten.de und seit 2011 Chef-Redakteur im Betten.de-Schlafmagazin.\",\"url\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/author\\\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"K\u00f6rpergerechte Betten: Worauf sollte ich achten? | Betten.at Magazin","description":"Worauf kommt es bei einem k\u00f6rpergerechten Bett an? Infos zu den K\u00f6rpertypen sowie zur Auswahl der passenden Matratze und vieles mehr.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.betten.at\/magazin\/koerpergerechte-betten-worauf-achten.html","og_locale":"de_DE","og_type":"article","og_title":"K\u00f6rpergerechte Betten: Worauf sollte ich achten? | Betten.at Magazin","og_description":"Worauf kommt es bei einem k\u00f6rpergerechten Bett an? Infos zu den K\u00f6rpertypen sowie zur Auswahl der passenden Matratze und vieles mehr.","og_url":"https:\/\/www.betten.at\/magazin\/koerpergerechte-betten-worauf-achten.html","article_published_time":"2016-11-28T16:00:08+00:00","article_modified_time":"2024-12-20T13:38:31+00:00","og_image":[{"width":435,"height":245,"url":"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/das-passende-bett-zu-meinem-koerper.jpg","type":"image\/jpeg"}],"author":"Ulrich Carsten","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Ulrich Carsten","Gesch\u00e4tzte Lesezeit":"27\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.betten.at\/magazin\/koerpergerechte-betten-worauf-achten.html#article","isPartOf":{"@id":"https:\/\/www.betten.at\/magazin\/koerpergerechte-betten-worauf-achten.html"},"author":{"name":"Ulrich Carsten","@id":"https:\/\/www.betten.de\/magazin\/#\/schema\/person\/7c1a4c0500ca2b101723693361b5750d"},"headline":"K\u00f6rpergerechte Betten: Worauf ist zu achten?","datePublished":"2016-11-28T16:00:08+00:00","dateModified":"2024-12-20T13:38:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.betten.at\/magazin\/koerpergerechte-betten-worauf-achten.html"},"wordCount":4646,"commentCount":0,"publisher":{"@id":"https:\/\/www.betten.de\/magazin\/#organization"},"image":{"@id":"https:\/\/www.betten.at\/magazin\/koerpergerechte-betten-worauf-achten.html#primaryimage"},"thumbnailUrl":"https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/das-passende-bett-zu-meinem-koerper.jpg","keywords":["Massivholzbetten","Polsterbetten"],"articleSection":["Medizin &amp; Wissenschaft"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.betten.at\/magazin\/koerpergerechte-betten-worauf-achten.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.betten.at\/magazin\/koerpergerechte-betten-worauf-achten.html","url":"https:\/\/www.betten.at\/magazin\/koerpergerechte-betten-worauf-achten.html","name":"K\u00f6rpergerechte Betten: Worauf sollte ich achten? | Betten.at Magazin","isPartOf":{"@id":"https:\/\/www.betten.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.betten.at\/magazin\/koerpergerechte-betten-worauf-achten.html#primaryimage"},"image":{"@id":"https:\/\/www.betten.at\/magazin\/koerpergerechte-betten-worauf-achten.html#primaryimage"},"thumbnailUrl":"https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/das-passende-bett-zu-meinem-koerper.jpg","datePublished":"2016-11-28T16:00:08+00:00","dateModified":"2024-12-20T13:38:31+00:00","description":"Worauf kommt es bei einem k\u00f6rpergerechten Bett an? Infos zu den K\u00f6rpertypen sowie zur Auswahl der passenden Matratze und vieles mehr.","breadcrumb":{"@id":"https:\/\/www.betten.at\/magazin\/koerpergerechte-betten-worauf-achten.html#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.betten.at\/magazin\/koerpergerechte-betten-worauf-achten.html"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.betten.at\/magazin\/koerpergerechte-betten-worauf-achten.html#primaryimage","url":"https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/das-passende-bett-zu-meinem-koerper.jpg","contentUrl":"https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/das-passende-bett-zu-meinem-koerper.jpg","width":435,"height":245},{"@type":"BreadcrumbList","@id":"https:\/\/www.betten.at\/magazin\/koerpergerechte-betten-worauf-achten.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.betten.at\/magazin"},{"@type":"ListItem","position":2,"name":"K\u00f6rpergerechte Betten: Worauf ist zu achten?"}]},{"@type":"WebSite","@id":"https:\/\/www.betten.de\/magazin\/#website","url":"https:\/\/www.betten.de\/magazin\/","name":"","description":"","publisher":{"@id":"https:\/\/www.betten.de\/magazin\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.betten.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.betten.de\/magazin\/#organization","name":"Betten.de","url":"https:\/\/www.betten.de\/magazin\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.betten.de\/magazin\/#\/schema\/logo\/image\/","url":"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/logo-1-1.jpg","contentUrl":"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/logo-1-1.jpg","width":500,"height":500,"caption":"Betten.de"},"image":{"@id":"https:\/\/www.betten.de\/magazin\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.betten.de\/magazin\/#\/schema\/person\/7c1a4c0500ca2b101723693361b5750d","name":"Ulrich Carsten","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/ucarsten-l-96x96.jpg","url":"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/ucarsten-l-96x96.jpg","contentUrl":"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/ucarsten-l-96x96.jpg","caption":"Ulrich Carsten"},"description":"Zertifizierter Bettenfachberater mit dem Schwerpunkt Matratzen in unserem Online-Shop Betten.de und seit 2011 Chef-Redakteur im Betten.de-Schlafmagazin.","url":"https:\/\/www.betten.de\/magazin\/author\/admin"}]}},"lang":"de-at","translations":{"de-at":33855,"de-de":30464},"pll_sync_post":{},"_links":{"self":[{"href":"https:\/\/www.betten.at\/magazin\/wp-json\/wp\/v2\/posts\/33855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.betten.at\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.betten.at\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.betten.at\/magazin\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.betten.at\/magazin\/wp-json\/wp\/v2\/comments?post=33855"}],"version-history":[{"count":3,"href":"https:\/\/www.betten.at\/magazin\/wp-json\/wp\/v2\/posts\/33855\/revisions"}],"predecessor-version":[{"id":49309,"href":"https:\/\/www.betten.at\/magazin\/wp-json\/wp\/v2\/posts\/33855\/revisions\/49309"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.betten.at\/magazin\/wp-json\/wp\/v2\/media\/30517"}],"wp:attachment":[{"href":"https:\/\/www.betten.at\/magazin\/wp-json\/wp\/v2\/media?parent=33855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.betten.at\/magazin\/wp-json\/wp\/v2\/categories?post=33855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.betten.at\/magazin\/wp-json\/wp\/v2\/tags?post=33855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}