﻿
{"id":34255,"date":"2023-03-20T06:08:26","date_gmt":"2023-03-20T05:08:26","guid":{"rendered":"http:\/\/www.betten.de\/magazin\/?p=34255"},"modified":"2023-03-20T07:22:21","modified_gmt":"2023-03-20T06:22:21","slug":"schlafen-schlaf-mittagsschlaf","status":"publish","type":"post","link":"https:\/\/www.betten.at\/magazin\/schlafen-schlaf-mittagsschlaf.html","title":{"rendered":"Mittagsschlaf"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignright size-full wp-image-816\" style=\"border: 0pt none;\" title=\"Mittagsschlaf und Power-Napping\" src=\"\/magazin\/wp-content\/uploads\/mittagsschlaf.jpg\" alt=\"Mann macht einen Mittagschlaf am Schreibtisch\"\/>In Deutschland zieht sich ungef\u00e4hr ein F\u00fcnftel der Bev\u00f6lkerung mittags zu einem Mittagsschlaf zur\u00fcck. In erster Linie sind es dabei die Rentner und Nichterwerbst\u00e4tigen, die es sich &#8222;leisten&#8220; k\u00f6nnen, mittags zu schlafen. F\u00fcr viele dieser Mittagsschl\u00e4fer ist der kurze Schlaf am Tag zu einem biologischen Grundbed\u00fcrfnis geworden, auf das sie nur schwer verzichten k\u00f6nnen und wollen.<\/p>\n<p>Der Mittagsschlaf kann auch f\u00fcr arbeitende Personen eine wahre Wohltat sein und zur Leistungssteigerung beitragen. Erfahren Sie jetzt mehr \u00fcber den Mittagsschlaf im Allgemeinen, den Mittagsschlaf in anderen L\u00e4ndern und die moderne Variante des B\u00fcroschlafs das Power-Napping.<br \/>\n<strong><br \/>\n<!--more Hier weiterlesen: Mittagsschlaf--><\/strong><\/p>\n<h2>Mittagsschlaf im Alter<\/h2>\n<p>Mehr als die H\u00e4lfte aller Befragten im Alter von 65 bis 83 Jahren gaben bei einer Umfrage an, dass sie oft oder t\u00e4glich einen Mittagsschlaf halten.\u00a0 Das vermehrte Schlafen am Tag steht bei \u00e4lteren Menschen in Verbindung mit einem reduzierten Nachtschlaf. Im Alter scheint sich bei vielen Menschen ein mehrphasiges Schlafmuster zu entwickeln, das Schlaf am Tag einschlie\u00dft, wie es auch in der fr\u00fchkindlichen Entwicklung typisch ist.<\/p>\n<h2>Power-Napping &#8211; moderner B\u00fcroschlaf<\/h2>\n<p>Schlafexperten sind sich einig, dass ein Mittagsschlaf w\u00e4hrend der Arbeitszeit &#8211; auch als Power-Napping bezeichnet (vom englischen &#8222;nap&#8220; f\u00fcr &#8222;Nickerchen&#8220;) absolut empfehlenswert ist. Unsere innere Uhr ist n\u00e4mlich um die Mittagszeit herum auf eine Ruhephase eingestellt. Dieses wurde auch in so genannten Bunkerexperimenten best\u00e4tigt, wo Personen f\u00fcr eine Studie drei Tage lang vollkommen von der Umwelt isoliert wurden. Dabei war ihnen weder Tages- noch Uhrzeit bekannt und es gab nichts, was sie erledigen mussten. Unter diesen Versuchsbedingungen g\u00f6nnten sich alle Probanten auch am Tage ein Schl\u00e4fchen.<\/p>\n<p>Hierzulande konnte sich der B\u00fcroschlaf &#8211; das Power-Napping jedoch noch nicht wirklich etablieren, obwohl Studien belegen, dass ein Kurzschlaf am Mittag mit einer Dauer von rund 20 Minuten zu einer Leistungserh\u00f6hung f\u00fchrt.<\/p>\n<h2>Siesta &#8211; Mittagsschlaf in vielen L\u00e4ndern ganz normal<\/h2>\n<p>In vielen L\u00e4ndern &#8211; insbesondere im Mittelmeerraum &#8211; ist es vollkommen \u00fcblich und normal, mittags zu schlafen &#8211; Siesta zu halten. Wissenschaftliche Untersuchungen haben in diesem Zusammenhang ergeben, dass klimatische Gegebenheiten zu einer Beibehaltung des biphasischen Schlafmusters, das Kinder im Vorschulalter typischerweise zeigen, f\u00fchren k\u00f6nnen.<\/p>\n<h2>Mittagsschlaf &#8211; ein Grundrecht in China<\/h2>\n<p>In China wird der Mittagsschlaf als Xiu-xi bezeichnet und von vielen Menschen zur Erholung genutzt. In der chinesischen Verfassung ist der Mittagsschlaf in Artikel 49 gesetzlich verankert, wo es he\u00dft: &#8222;Das arbeitende Volk hat das Recht zu ruhen.&#8220;. Im Anschluss an das Mittagessen legen sich viele Chinesen in Fabriken und B\u00fcros deshalb regelm\u00e4\u00dfig zur Ruhe, bevor sie zur\u00fcck an ihre Arbeit gehen.<\/p>\n<h2>Extreme-Power-Napping &#8211; ein Muss in Japan<\/h2>\n<p>Die Japaner haben sich im Gros so sehr der Arbeit verschrieben, das f\u00fcr den notwendigen Nachtschlaf meist kaum Zeit bleibt. Um die auftretenden Schlafdefizite und die damit verbundenen Beeintr\u00e4chtigungen auszugleichen, haben sich die Japaner zu wahren Power-Napping-Spezialisten entwickelt. Wann immer sich am Tage die Gelegenheit f\u00fcr ein Nickerchen bietet, wird diese genutzt. So schlafen einige Japaner exakt die Zeit, die sie im Zug auf dem Weg zur Arbeit oder von der Arbeit nach Hause verbringen. Dabei sind sie so genau programmiert, dass sie automatisch aufwachen, wenn der Zug das gew\u00fcnschte Ziel erreicht. Selbst in Meetings und Besprechungen schrecken die Japaner nicht davor zur\u00fcck, sich kurzzeitig f\u00fcr ein Nickerchen aus der Runde &#8222;auszuklinken&#8220;, was allgemein toleriert und akzeptiert wird. Die Japaner selber bezeichnen den Mittagsschlaf als &#8222;Inemuri&#8220;, was soviel wie &#8222;anwesend sein und schlafen&#8220; bedeutet.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ruhepause und Auszeit am Tag. Details zum Mittagsschlaf und zum Power-Napping. Durch Schlaf am Tag besser f\u00fchlen und mehr leisten.<\/p>\n","protected":false},"author":14,"featured_media":46343,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[416],"tags":[],"class_list":["post-34255","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-schlaf"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mittagsschlaf | Power-Napping | Schlaf am Tag<\/title>\n<meta name=\"description\" content=\"Hintergr\u00fcnde zu Mittagsschlaf &amp; Power-Napping. Wie ein Schl\u00e4fchen am Tage die Leistungsf\u00e4higkeit und das Wohlbefinden steigern kann.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.betten.at\/magazin\/schlafen-schlaf-mittagsschlaf.html\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mittagsschlaf | Power-Napping | Schlaf am Tag\" \/>\n<meta property=\"og:description\" content=\"Hintergr\u00fcnde zu Mittagsschlaf &amp; Power-Napping. Wie ein Schl\u00e4fchen am Tage die Leistungsf\u00e4higkeit und das Wohlbefinden steigern kann.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.betten.at\/magazin\/schlafen-schlaf-mittagsschlaf.html\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-20T05:08:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-20T06:22:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/tagesmuedigkeit.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"435\" \/>\n\t<meta property=\"og:image:height\" content=\"245\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ulrich Carsten\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ulrich Carsten\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/schlafen-schlaf-mittagsschlaf.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/schlafen-schlaf-mittagsschlaf.html\"},\"author\":{\"name\":\"Ulrich Carsten\",\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#\\\/schema\\\/person\\\/7c1a4c0500ca2b101723693361b5750d\"},\"headline\":\"Mittagsschlaf\",\"datePublished\":\"2023-03-20T05:08:26+00:00\",\"dateModified\":\"2023-03-20T06:22:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/schlafen-schlaf-mittagsschlaf.html\"},\"wordCount\":585,\"publisher\":{\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/schlafen-schlaf-mittagsschlaf.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/wp-content\\\/uploads\\\/tagesmuedigkeit.jpg\",\"articleSection\":[\"Schlaf-Basics\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/schlafen-schlaf-mittagsschlaf.html\",\"url\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/schlafen-schlaf-mittagsschlaf.html\",\"name\":\"Mittagsschlaf | Power-Napping | Schlaf am Tag\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/schlafen-schlaf-mittagsschlaf.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/schlafen-schlaf-mittagsschlaf.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/wp-content\\\/uploads\\\/tagesmuedigkeit.jpg\",\"datePublished\":\"2023-03-20T05:08:26+00:00\",\"dateModified\":\"2023-03-20T06:22:21+00:00\",\"description\":\"Hintergr\u00fcnde zu Mittagsschlaf & Power-Napping. Wie ein Schl\u00e4fchen am Tage die Leistungsf\u00e4higkeit und das Wohlbefinden steigern kann.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/schlafen-schlaf-mittagsschlaf.html#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.betten.at\\\/magazin\\\/schlafen-schlaf-mittagsschlaf.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/schlafen-schlaf-mittagsschlaf.html#primaryimage\",\"url\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/wp-content\\\/uploads\\\/tagesmuedigkeit.jpg\",\"contentUrl\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/wp-content\\\/uploads\\\/tagesmuedigkeit.jpg\",\"width\":435,\"height\":245},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/schlafen-schlaf-mittagsschlaf.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.betten.at\\\/magazin\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mittagsschlaf\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#organization\",\"name\":\"Betten.de\",\"url\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/wp-content\\\/uploads\\\/logo-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/wp-content\\\/uploads\\\/logo-1-1.jpg\",\"width\":500,\"height\":500,\"caption\":\"Betten.de\"},\"image\":{\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#\\\/schema\\\/person\\\/7c1a4c0500ca2b101723693361b5750d\",\"name\":\"Ulrich Carsten\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/wp-content\\\/uploads\\\/ucarsten-l-96x96.jpg\",\"url\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/wp-content\\\/uploads\\\/ucarsten-l-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/wp-content\\\/uploads\\\/ucarsten-l-96x96.jpg\",\"caption\":\"Ulrich Carsten\"},\"description\":\"Zertifizierter Bettenfachberater mit dem Schwerpunkt Matratzen in unserem Online-Shop Betten.de und seit 2011 Chef-Redakteur im Betten.de-Schlafmagazin.\",\"url\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/author\\\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mittagsschlaf | Power-Napping | Schlaf am Tag","description":"Hintergr\u00fcnde zu Mittagsschlaf & Power-Napping. Wie ein Schl\u00e4fchen am Tage die Leistungsf\u00e4higkeit und das Wohlbefinden steigern kann.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.betten.at\/magazin\/schlafen-schlaf-mittagsschlaf.html","og_locale":"de_DE","og_type":"article","og_title":"Mittagsschlaf | Power-Napping | Schlaf am Tag","og_description":"Hintergr\u00fcnde zu Mittagsschlaf & Power-Napping. Wie ein Schl\u00e4fchen am Tage die Leistungsf\u00e4higkeit und das Wohlbefinden steigern kann.","og_url":"https:\/\/www.betten.at\/magazin\/schlafen-schlaf-mittagsschlaf.html","article_published_time":"2023-03-20T05:08:26+00:00","article_modified_time":"2023-03-20T06:22:21+00:00","og_image":[{"width":435,"height":245,"url":"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/tagesmuedigkeit.jpg","type":"image\/jpeg"}],"author":"Ulrich Carsten","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Ulrich Carsten","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.betten.at\/magazin\/schlafen-schlaf-mittagsschlaf.html#article","isPartOf":{"@id":"https:\/\/www.betten.at\/magazin\/schlafen-schlaf-mittagsschlaf.html"},"author":{"name":"Ulrich Carsten","@id":"https:\/\/www.betten.de\/magazin\/#\/schema\/person\/7c1a4c0500ca2b101723693361b5750d"},"headline":"Mittagsschlaf","datePublished":"2023-03-20T05:08:26+00:00","dateModified":"2023-03-20T06:22:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.betten.at\/magazin\/schlafen-schlaf-mittagsschlaf.html"},"wordCount":585,"publisher":{"@id":"https:\/\/www.betten.de\/magazin\/#organization"},"image":{"@id":"https:\/\/www.betten.at\/magazin\/schlafen-schlaf-mittagsschlaf.html#primaryimage"},"thumbnailUrl":"https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/tagesmuedigkeit.jpg","articleSection":["Schlaf-Basics"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.betten.at\/magazin\/schlafen-schlaf-mittagsschlaf.html","url":"https:\/\/www.betten.at\/magazin\/schlafen-schlaf-mittagsschlaf.html","name":"Mittagsschlaf | Power-Napping | Schlaf am Tag","isPartOf":{"@id":"https:\/\/www.betten.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.betten.at\/magazin\/schlafen-schlaf-mittagsschlaf.html#primaryimage"},"image":{"@id":"https:\/\/www.betten.at\/magazin\/schlafen-schlaf-mittagsschlaf.html#primaryimage"},"thumbnailUrl":"https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/tagesmuedigkeit.jpg","datePublished":"2023-03-20T05:08:26+00:00","dateModified":"2023-03-20T06:22:21+00:00","description":"Hintergr\u00fcnde zu Mittagsschlaf & Power-Napping. Wie ein Schl\u00e4fchen am Tage die Leistungsf\u00e4higkeit und das Wohlbefinden steigern kann.","breadcrumb":{"@id":"https:\/\/www.betten.at\/magazin\/schlafen-schlaf-mittagsschlaf.html#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.betten.at\/magazin\/schlafen-schlaf-mittagsschlaf.html"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.betten.at\/magazin\/schlafen-schlaf-mittagsschlaf.html#primaryimage","url":"https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/tagesmuedigkeit.jpg","contentUrl":"https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/tagesmuedigkeit.jpg","width":435,"height":245},{"@type":"BreadcrumbList","@id":"https:\/\/www.betten.at\/magazin\/schlafen-schlaf-mittagsschlaf.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.betten.at\/magazin"},{"@type":"ListItem","position":2,"name":"Mittagsschlaf"}]},{"@type":"WebSite","@id":"https:\/\/www.betten.de\/magazin\/#website","url":"https:\/\/www.betten.de\/magazin\/","name":"","description":"","publisher":{"@id":"https:\/\/www.betten.de\/magazin\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.betten.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.betten.de\/magazin\/#organization","name":"Betten.de","url":"https:\/\/www.betten.de\/magazin\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.betten.de\/magazin\/#\/schema\/logo\/image\/","url":"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/logo-1-1.jpg","contentUrl":"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/logo-1-1.jpg","width":500,"height":500,"caption":"Betten.de"},"image":{"@id":"https:\/\/www.betten.de\/magazin\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.betten.de\/magazin\/#\/schema\/person\/7c1a4c0500ca2b101723693361b5750d","name":"Ulrich Carsten","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/ucarsten-l-96x96.jpg","url":"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/ucarsten-l-96x96.jpg","contentUrl":"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/ucarsten-l-96x96.jpg","caption":"Ulrich Carsten"},"description":"Zertifizierter Bettenfachberater mit dem Schwerpunkt Matratzen in unserem Online-Shop Betten.de und seit 2011 Chef-Redakteur im Betten.de-Schlafmagazin.","url":"https:\/\/www.betten.de\/magazin\/author\/admin"}]}},"lang":"de-at","translations":{"de-at":34255,"de-de":810},"pll_sync_post":{},"_links":{"self":[{"href":"https:\/\/www.betten.at\/magazin\/wp-json\/wp\/v2\/posts\/34255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.betten.at\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.betten.at\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.betten.at\/magazin\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.betten.at\/magazin\/wp-json\/wp\/v2\/comments?post=34255"}],"version-history":[{"count":0,"href":"https:\/\/www.betten.at\/magazin\/wp-json\/wp\/v2\/posts\/34255\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.betten.at\/magazin\/wp-json\/wp\/v2\/media\/46343"}],"wp:attachment":[{"href":"https:\/\/www.betten.at\/magazin\/wp-json\/wp\/v2\/media?parent=34255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.betten.at\/magazin\/wp-json\/wp\/v2\/categories?post=34255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.betten.at\/magazin\/wp-json\/wp\/v2\/tags?post=34255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}