﻿
{"id":34279,"date":"2011-11-28T09:54:45","date_gmt":"2011-11-28T08:54:45","guid":{"rendered":"http:\/\/www.betten.de\/magazin\/?p=34279"},"modified":"2022-09-06T14:10:22","modified_gmt":"2022-09-06T12:10:22","slug":"schlafen-schlafstoerungen-schnarchen","status":"publish","type":"post","link":"https:\/\/www.betten.at\/magazin\/schlafen-schlafstoerungen-schnarchen.html","title":{"rendered":"Schnarchen kann krank machen"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignright size-full wp-image-622\" style=\"border: 0pt none;\" title=\"Schnarchen: l\u00e4stig und nicht ungef\u00e4hrlich\" src=\"\/magazin\/wp-content\/uploads\/schnarchen-schlaf-1.jpg\" alt=\"Zeichnung einer schnarchenden Person\"\/>Wohl jeder kennt das typische Ger\u00e4usch, das durch Schnarchen hervorgerufen wird.\u00a0 Schnarchen geh\u00f6rt zu den vier h\u00e4ufigsten Schlafst\u00f6rungen und ist nicht nur l\u00e4stig f\u00fcr den Bettnachbarn, sondern kann auch ernsthaft krank machen. Die n\u00e4chtliche Bel\u00e4stigung und gro\u00dfe Herausforderung f\u00fcr jede Paarbeziehung bzw. Ehe wurde vom Schriftsteller Anthony Burgess perfekt auf den Punkt gebracht: &#8222;Lache, und die Welt lacht mit dir. Schnarche, und du schl\u00e4fst allein.&#8220;<\/p>\n<p>Wie entsteht das l\u00e4stige Ger\u00e4usch? Was kann man gegen Schnarchen unternehmen? Welche Gefahren gehen vom Schnarchen aus? Die Antworten auf diese und weitere Fragen finden Sie in unserem Artikel rund ums Schnarchen.<strong><!--more Hier weiterlesen: Schlafst\u00f6rung Schnarchen--><\/strong><\/p>\n<div id=\"inhaltsverzeichnis-fullw\" style=\"margin-top:50px;\">\n<div class=\"summary\">Inhaltsverzeichnis:<\/div>\n<ul>\n<li><a href=\"#ursache\">Wie kommt es zum Schnarchen und was passiert beim Schnarchen im K\u00f6rper?<\/a><\/li>\n<li><a href=\"#faktoren\">Welche Faktoren f\u00f6rdern das Schnarchen?<\/a><\/li>\n<li><a href=\"#lautstaerke\">Wie laut ist Schnarchen?<\/a><\/li>\n<li><a href=\"#arten\">Welche Arten von Schnarchen werden unterschieden?<\/a><\/li>\n<li><a href=\"#wer\">Wer schnarcht?<\/a><\/li>\n<li><a href=\"#hilfe\">Was kann man gegen Schnarchen tun?<\/a><\/li>\n<li><a href=\"#risiken\">Welche Risiken gehen vom Schnarchen aus?<\/a><\/li>\n<\/ul>\n<\/div>\n<p><a name=\"ursache\"><\/a><\/p>\n<h2>Wie kommt es zum Schnarchen und was passiert beim Schnarchen im K\u00f6rper?<\/h2>\n<p>Zuerst handelt es sich beim Schnarchen um ein Ger\u00e4usch, das im Schlaf meistens beim Einatmen &#8211; lediglich selten auch beim Ausatmen, in den oberen Atemwegen entsteht. Um dieses typische Schnarchger\u00e4usch in wachem Zustand zu erzeugen, m\u00fcssen wir nur den Mund leicht \u00f6ffnen, die Zunge nach hinten nehmen, die Rachenmuskulatur entspannen und andauernd einatmen. Gaumensegel und Rachenwand knattern dann direkt vor sich hin und rufen das altbekannte, verhasste Schnarchger\u00e4usch hervor.<\/p>\n<p>Unser Rachen ist mit Weichteilen (Gaumensegel, Z\u00e4pfchen und Schleimhautfalten) ausgekleidet. Atmen wir nun in erster Linie durch den Mund, k\u00f6nnen diese Weichteile durch den Sog der Luftstr\u00f6mung in Schwingungen versetzt werden. Zus\u00e4tzlich m\u00fcssen als Voraussetzung f\u00fcr das Schnarchen in der Region der oberen Luftwege Verengungen vorliegen, welche Turbulenzen beim Einatmen m\u00f6glich machen.<\/p>\n<p>Bei jedem Menschen l\u00e4sst im Schlaf die Muskelspannung nach. Im Zuge dieser Muskelentspannung kommt es sowohl beim Schnarcher als auch beim ruhigen Schl\u00e4fer ebenfalls zum Erschlaffen der Muskeln im Rachen und des Zungenmuskels (zieht die Zunge nach vorne). In der Folge n\u00e4hern sich Rachenwand, weicher Gaumen und Zungenwurzel beim Einatmen durch den Sog, der von der Lunge ausgeht, und durch die reduzierte Muskelspannung einander an. Normalerweise ist die verbleibende Muskelspannung allerdings gro\u00df genug, um den Rachen so weit offen zu halten, dass die Luft ohne Behinderung hindurchstr\u00f6men kann.<\/p>\n<p>Aufgrund der entspannten Rachenmuskulatur und Zungenmuskulatur kommt es beim Schnarcher zu Verengungen. Teilweise verf\u00fcgt der Schnarcher zus\u00e4tzlich auch noch \u00fcber weitere Engstellen in den oberen Atemwegen wie vergr\u00f6\u00dferte Mandeln oder ein vergr\u00f6\u00dfertes Z\u00e4pfchen. Die Luft str\u00f6mt in diesen engen Bereichen beim Einatmen schneller. Durch den beschleunigten Luftstrom werden die Weichteile im Rachen vermehrt in Vibrationen versetzt. Das &#8222;Schnarchkonzert&#8220; beginnt.<\/p>\n<p>Zum Schnarchen kommt es besonders dann, wenn der Schlafende auf dem R\u00fccken liegt. Die Ursache hierf\u00fcr ist in der Schwerkraft zu finden. In der R\u00fcckenlage f\u00e4llt die Zungenwurzel leicht nach hinten zur Rachenwand hin, und da insbesondere in Tiefschlafphasen eine Entspannung des Hauptzungenmuskels vorliegt, erfolgt kein Gegensteuern zur Schwerkraft. Eine Enge im Rachenraum entsteht, wodurch sich der Luftstrom beschleunigt und die Weichteile im Rachen anfangen zu schwingen &#8211; der Schl\u00e4fer schnarcht. In R\u00fcckenlage fangen oft auch viele Menschen an zu schnarchen, die in seitlicher Position absolut ger\u00e4uschlos schlafen.<\/p>\n<hr \/>\n<p><a name=\"faktoren\"><\/a><\/p>\n<h2>Welche Faktoren f\u00f6rdern das Schnarchen?<\/h2>\n<p>Neben der R\u00fcckenlage zum Schlafen, die schnell zum Garanten f\u00fcr Schnarchen wird, beg\u00fcnstigt Alkoholgenuss das Schnarchen ungemein. Auch alles, was die Atmung reizt oder beeintr\u00e4chtigt (Rauchen, Allergien, einige entspannende Medikamente), wirkt sich f\u00f6rderlich auf das Schnarchen aus. Daneben ist \u00dcbergewicht ein weiterer Hauptausl\u00f6ser f\u00fcr das Schnarchen. Weiterhin k\u00f6nnen ebenfalls k\u00f6rperliche Besonderheiten und Umst\u00e4nde, Schnarchen hervorrufen oder verst\u00e4rken. Dazu geh\u00f6ren beispielsweise kleine Unterkiefer, gro\u00dfe Zungen, schiefe Nasenscheidew\u00e4nde, vergr\u00f6\u00dferte Mandeln oder geschwollene Nasenmuscheln.<\/p>\n<hr \/>\n<p><a name=\"lautstaerke\"><\/a><\/p>\n<h2>Wie laut ist Schnarchen?<\/h2>\n<p>Die Lautst\u00e4rke beim Schnarchen variiert je nach Auspr\u00e4gung der Schlafst\u00f6rung. Normale Schnarcher erreichen in der Regel einen Schallpegel zwischen 40 und 45 Dezibel, was in etwa mit einem &#8222;Fl\u00fcstern&#8220; gleichzusetzen ist. Schnarcher, deren Schnarchen ein Anzeichen f\u00fcr eine Schlafapnoe ist, werden jedoch deutlich lauter. Das Schnarchen erreicht hierbei oft Lautst\u00e4rken von 70 Dezibel und mehr. Wobei 70 Dezibel ungef\u00e4hr die Lautst\u00e4rke eines normalen Gespr\u00e4chs sind.<\/p>\n<p>Der Lautst\u00e4rken-Rekord im Schnarchen (Guinness-Rekord) wird vom aus dem schwedischen Kumala stammenden Kare Walkert gehalten und liegt bei sagenhaften 93 Dezibel. Um eine etwas bessere Vorstellung vom Ausma\u00df einer derartigen Schnarchbel\u00e4stigung zu bekommen: starker Stra\u00dfenverkehr verursacht einen Ger\u00e4uschpegel von etwa 90 Dezibel. Wer also neben Kare Walkert zu seinen besten Schnarchzeiten schlafen will, kann sich auch gleich neben die Autobahn legen und versuchen dort zur Ruhe zu kommen.<\/p>\n<hr \/>\n<p><a name=\"arten\"><\/a><\/p>\n<h2>Welche Arten von Schnarchen werden unterschieden?<\/h2>\n<p>Schnarchen ist nicht gleich schnarchen. In der Medizin werden beim Schnarchen beispielsweise Unterschiede nach den Weichteilen, die das Schnarchger\u00e4usch ausl\u00f6sen, gemacht. So wird das Schnarchen, welches durch das Gaumensegel ausgel\u00f6st wird, als velares Schnarchen bezeichnet. Wird das Schnarchen durch die im Rachen befindlichen Schleimfalten verursacht, ist die Rede vom pharyngealen Schnarchen. Schnarchen kann jedoch auch im &#8222;kombinierter&#8220; Form vorliegen, also, dass das Schnarchen sowohl durch Vibrationen des Gaumensegels als auch durch Schwingungen der Schleimfalten verursacht wird.<\/p>\n<p>Das normale Schnarchen, das medizinisch unbedenklich ist, wird au\u00dferdem als prim\u00e4res oder habituelles Schnarchen bezeichnet. Von diesem Schnarchen sind etwa ein Drittel aller erwachsenen Deutschen betroffen. Dabei werden Menschen, die nur gelegentlich schnarchen nicht mitgerechnet.<\/p>\n<hr \/>\n<p><a name=\"wer\"><\/a><\/p>\n<h2>Wer schnarcht?<\/h2>\n<p>In j\u00fcngeren Jahren schnarchen mehr M\u00e4nner als Frauen. Man geht davon aus, dass etwa vier von zehn M\u00e4nnern und drei von zehn Frauen schnarchen. Das die Zahl der schnarchenden Frauen in j\u00fcngeren Jahren geringer ausf\u00e4llt, ist wahrscheinlich auf das Geschlechtshormon \u00d6strogen zur\u00fcckzuf\u00fchren, welches das Rachengewebe besser in Form h\u00e4lt.<\/p>\n<p>Im Alter wird allgemein mehr geschnarcht, was damit zusammenh\u00e4ngt, dass die Weichteile im Rachen im Alter erschlaffen und so leichter in Vibrationen geraten. Dieses gilt gleicherma\u00dfen f\u00fcr M\u00e4nner wie f\u00fcr Frauen, weshalb es bei \u00e4lteren Menschen keine unterschiedliche Verteilung mehr gibt und Schnarcher bei beiden Geschlechtern in gleicher Relation vorkommen.<\/p>\n<p>Auch bei Kindern kann gelegentlich schnarchen beobachtet bzw. &#8222;belauscht&#8220; werden. Schnarchen bei kindlichen Schl\u00e4fern ist h\u00e4ufig auf vergr\u00f6\u00dferte Mandeln zur\u00fcckzuf\u00fchren.<\/p>\n<hr \/>\n<p><a name=\"hilfe\"><\/a><\/p>\n<h2>Was kann man gegen Schnarchen tun?<\/h2>\n<p>Schnarchen kann durch das Tragen einer Gebissschiene, die individuell vom Zahnarzt oder Kieferorthop\u00e4den hergestellt bzw. angepasst wird, vermindert oder sogar ganz abgestellt werden. Eine Gebissschiene f\u00fcr Schnarcher ist wie ein Mundschutz f\u00fcr Boxer geformt. Sie wird nachts \u00fcber den Z\u00e4hnen getragen, wobei sie den Unterkiefer etwas nach vorne h\u00e4lt, was den Luftweg auf der hinteren Seite des Rachens offen h\u00e4lt.<\/p>\n<p>Auch im Handel werden eine Reihe von Hilfsmitteln angeboten. Dazu geh\u00f6ren beispielsweise die Nasenpflaster, wobei es keine schl\u00fcssigen Beweise f\u00fcr eine Wirksamkeit gibt. Spezielle Antischnarchkissen sollen angeblich den Kopf in einer Position halten, wo die Atemwege frei bleiben. Weit verbreitet sind auch Ger\u00e4te f\u00fcr das Handgelenk, die dem Schlafenden im Fall von Schnarchen einen leichten elektrischen Schlag versetzen und ihn so zum Positionswechsel bewegen sollen.<\/p>\n<p>Um nachts nicht in die R\u00fcckenlage &#8222;zu verfallen&#8220;, kann es hilfreich sein, einen Tennisball in das R\u00fcckenteil von Schlafanzug oder Nachthemd einzun\u00e4hen, der das Liegen auf dem R\u00fccken \u00e4u\u00dferst unangenehm werden l\u00e4sst. Gelegentlich werden derartige &#8222;Antischnarchhemden&#8220; mit einer Verdickung im R\u00fcckenteil auch schon fertig zum Kauf angeboten.<\/p>\n<p>Auch eine Operation ist denkbar. Dazu muss jedoch sichergestellt sein, dass das Schnarchen nicht im Zusammenhang mit einer Schlafapnoe steht. Bevor sich ein Schnarcher operieren l\u00e4sst, sind deshalb unbedingt umfassende Tests im Schlaflabor und weitere medizinische Untersuchungen notwendig. Es gibt unterschiedliche Operationsmethoden gegen Schnarchen, die jedoch nicht alle klinisch erprobt und oft auch nur bedingt erfolgversprechend sind. Hier sollte man sich unbedingt genau beraten lassen.<\/p>\n<p>Unabh\u00e4ngig von allen vorgestellten Ma\u00dfnahmen und Hilfsmitteln, sollten Schnarcher, generell auf ein gesundes K\u00f6rpergewicht achten und vor dem Schlafengehen auf Alkohol und die Einnahme bestimmter Medikamente verzichten. Im Erk\u00e4ltungsfall bzw. bei Schnupfen, ist es au\u00dferdem ratsam, mehrfach t\u00e4glich Nasensp\u00fclungen durchzuf\u00fchren. Der K\u00f6rper sollte weiterhin beim Schlafen leicht erh\u00f6ht positioniert werden. Die R\u00fcckenlage sollte weitgehend vermieden werden.<\/p>\n<hr \/>\n<p><a name=\"risiken\"><\/a><\/p>\n<h2>Welche Risiken gehen vom Schnarchen aus?<\/h2>\n<p>Wie bereits erw\u00e4hnt, kann Schnarchen ein Hinweis auf eine <a href=\"\/magazin\/schlafapnoe.html\">Schlafapnoe<\/a> sein.<\/p>\n<p>Daneben gibt es medizinische Hinweise, die darauf hindeuten, dass schnarchende Menschen ein erh\u00f6htes Risiko f\u00fcr Bluthochdruck aufweisen. Au\u00dferdem soll es bei Frauen, die schnarchen, eher zu einer Risikoschwangerschaft mit negativen Folgen f\u00fcr den F\u00f6tus kommen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eine der bekanntesten Schlafst\u00f6rungen ist das Schnarchen. Im Schlaf-Magazin informieren wir Sie umfassend zum Thema Schnarchen, erkl\u00e4ren die Hintergr\u00fcnde, stellen die Gefahren vor und geben Tipps zur Abhilfe<\/p>\n","protected":false},"author":14,"featured_media":46323,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[420],"tags":[],"class_list":["post-34279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-schlafstoerungen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Schnarchen - verbreitete Schlafst\u00f6rung | Betten.at Schlaf-Magazin<\/title>\n<meta name=\"description\" content=\"L\u00e4stige Schlafst\u00f6rung: Schnarchen. Informieren Sie sich im Betten.at Schlaf-Magazin \u00fcber die Hintergr\u00fcnde des Schnarchens. Tipps zur Abhilfe.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.betten.at\/magazin\/schlafen-schlafstoerungen-schnarchen.html\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schnarchen - verbreitete Schlafst\u00f6rung | Betten.at Schlaf-Magazin\" \/>\n<meta property=\"og:description\" content=\"L\u00e4stige Schlafst\u00f6rung: Schnarchen. Informieren Sie sich im Betten.at Schlaf-Magazin \u00fcber die Hintergr\u00fcnde des Schnarchens. Tipps zur Abhilfe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.betten.at\/magazin\/schlafen-schlafstoerungen-schnarchen.html\" \/>\n<meta property=\"article:published_time\" content=\"2011-11-28T08:54:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-06T12:10:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/schnarchen-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"435\" \/>\n\t<meta property=\"og:image:height\" content=\"245\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ulrich Carsten\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ulrich Carsten\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/schlafen-schlafstoerungen-schnarchen.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/schlafen-schlafstoerungen-schnarchen.html\"},\"author\":{\"name\":\"Ulrich Carsten\",\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#\\\/schema\\\/person\\\/7c1a4c0500ca2b101723693361b5750d\"},\"headline\":\"Schnarchen kann krank machen\",\"datePublished\":\"2011-11-28T08:54:45+00:00\",\"dateModified\":\"2022-09-06T12:10:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/schlafen-schlafstoerungen-schnarchen.html\"},\"wordCount\":1439,\"publisher\":{\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/schlafen-schlafstoerungen-schnarchen.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/wp-content\\\/uploads\\\/schnarchen-2.jpg\",\"articleSection\":[\"Schlafst\u00f6rungen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/schlafen-schlafstoerungen-schnarchen.html\",\"url\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/schlafen-schlafstoerungen-schnarchen.html\",\"name\":\"Schnarchen - verbreitete Schlafst\u00f6rung | Betten.at Schlaf-Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/schlafen-schlafstoerungen-schnarchen.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/schlafen-schlafstoerungen-schnarchen.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/wp-content\\\/uploads\\\/schnarchen-2.jpg\",\"datePublished\":\"2011-11-28T08:54:45+00:00\",\"dateModified\":\"2022-09-06T12:10:22+00:00\",\"description\":\"L\u00e4stige Schlafst\u00f6rung: Schnarchen. Informieren Sie sich im Betten.at Schlaf-Magazin \u00fcber die Hintergr\u00fcnde des Schnarchens. Tipps zur Abhilfe.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/schlafen-schlafstoerungen-schnarchen.html#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.betten.at\\\/magazin\\\/schlafen-schlafstoerungen-schnarchen.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/schlafen-schlafstoerungen-schnarchen.html#primaryimage\",\"url\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/wp-content\\\/uploads\\\/schnarchen-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/wp-content\\\/uploads\\\/schnarchen-2.jpg\",\"width\":435,\"height\":245},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.betten.at\\\/magazin\\\/schlafen-schlafstoerungen-schnarchen.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.betten.at\\\/magazin\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Schnarchen kann krank machen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#organization\",\"name\":\"Betten.de\",\"url\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/wp-content\\\/uploads\\\/logo-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/wp-content\\\/uploads\\\/logo-1-1.jpg\",\"width\":500,\"height\":500,\"caption\":\"Betten.de\"},\"image\":{\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#\\\/schema\\\/person\\\/7c1a4c0500ca2b101723693361b5750d\",\"name\":\"Ulrich Carsten\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/wp-content\\\/uploads\\\/ucarsten-l-96x96.jpg\",\"url\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/wp-content\\\/uploads\\\/ucarsten-l-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/wp-content\\\/uploads\\\/ucarsten-l-96x96.jpg\",\"caption\":\"Ulrich Carsten\"},\"description\":\"Zertifizierter Bettenfachberater mit dem Schwerpunkt Matratzen in unserem Online-Shop Betten.de und seit 2011 Chef-Redakteur im Betten.de-Schlafmagazin.\",\"url\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/author\\\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Schnarchen - verbreitete Schlafst\u00f6rung | Betten.at Schlaf-Magazin","description":"L\u00e4stige Schlafst\u00f6rung: Schnarchen. Informieren Sie sich im Betten.at Schlaf-Magazin \u00fcber die Hintergr\u00fcnde des Schnarchens. Tipps zur Abhilfe.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.betten.at\/magazin\/schlafen-schlafstoerungen-schnarchen.html","og_locale":"de_DE","og_type":"article","og_title":"Schnarchen - verbreitete Schlafst\u00f6rung | Betten.at Schlaf-Magazin","og_description":"L\u00e4stige Schlafst\u00f6rung: Schnarchen. Informieren Sie sich im Betten.at Schlaf-Magazin \u00fcber die Hintergr\u00fcnde des Schnarchens. Tipps zur Abhilfe.","og_url":"https:\/\/www.betten.at\/magazin\/schlafen-schlafstoerungen-schnarchen.html","article_published_time":"2011-11-28T08:54:45+00:00","article_modified_time":"2022-09-06T12:10:22+00:00","og_image":[{"width":435,"height":245,"url":"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/schnarchen-2.jpg","type":"image\/jpeg"}],"author":"Ulrich Carsten","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Ulrich Carsten","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.betten.at\/magazin\/schlafen-schlafstoerungen-schnarchen.html#article","isPartOf":{"@id":"https:\/\/www.betten.at\/magazin\/schlafen-schlafstoerungen-schnarchen.html"},"author":{"name":"Ulrich Carsten","@id":"https:\/\/www.betten.de\/magazin\/#\/schema\/person\/7c1a4c0500ca2b101723693361b5750d"},"headline":"Schnarchen kann krank machen","datePublished":"2011-11-28T08:54:45+00:00","dateModified":"2022-09-06T12:10:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.betten.at\/magazin\/schlafen-schlafstoerungen-schnarchen.html"},"wordCount":1439,"publisher":{"@id":"https:\/\/www.betten.de\/magazin\/#organization"},"image":{"@id":"https:\/\/www.betten.at\/magazin\/schlafen-schlafstoerungen-schnarchen.html#primaryimage"},"thumbnailUrl":"https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/schnarchen-2.jpg","articleSection":["Schlafst\u00f6rungen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.betten.at\/magazin\/schlafen-schlafstoerungen-schnarchen.html","url":"https:\/\/www.betten.at\/magazin\/schlafen-schlafstoerungen-schnarchen.html","name":"Schnarchen - verbreitete Schlafst\u00f6rung | Betten.at Schlaf-Magazin","isPartOf":{"@id":"https:\/\/www.betten.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.betten.at\/magazin\/schlafen-schlafstoerungen-schnarchen.html#primaryimage"},"image":{"@id":"https:\/\/www.betten.at\/magazin\/schlafen-schlafstoerungen-schnarchen.html#primaryimage"},"thumbnailUrl":"https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/schnarchen-2.jpg","datePublished":"2011-11-28T08:54:45+00:00","dateModified":"2022-09-06T12:10:22+00:00","description":"L\u00e4stige Schlafst\u00f6rung: Schnarchen. Informieren Sie sich im Betten.at Schlaf-Magazin \u00fcber die Hintergr\u00fcnde des Schnarchens. Tipps zur Abhilfe.","breadcrumb":{"@id":"https:\/\/www.betten.at\/magazin\/schlafen-schlafstoerungen-schnarchen.html#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.betten.at\/magazin\/schlafen-schlafstoerungen-schnarchen.html"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.betten.at\/magazin\/schlafen-schlafstoerungen-schnarchen.html#primaryimage","url":"https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/schnarchen-2.jpg","contentUrl":"https:\/\/www.betten.at\/magazin\/wp-content\/uploads\/schnarchen-2.jpg","width":435,"height":245},{"@type":"BreadcrumbList","@id":"https:\/\/www.betten.at\/magazin\/schlafen-schlafstoerungen-schnarchen.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.betten.at\/magazin"},{"@type":"ListItem","position":2,"name":"Schnarchen kann krank machen"}]},{"@type":"WebSite","@id":"https:\/\/www.betten.de\/magazin\/#website","url":"https:\/\/www.betten.de\/magazin\/","name":"","description":"","publisher":{"@id":"https:\/\/www.betten.de\/magazin\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.betten.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.betten.de\/magazin\/#organization","name":"Betten.de","url":"https:\/\/www.betten.de\/magazin\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.betten.de\/magazin\/#\/schema\/logo\/image\/","url":"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/logo-1-1.jpg","contentUrl":"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/logo-1-1.jpg","width":500,"height":500,"caption":"Betten.de"},"image":{"@id":"https:\/\/www.betten.de\/magazin\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.betten.de\/magazin\/#\/schema\/person\/7c1a4c0500ca2b101723693361b5750d","name":"Ulrich Carsten","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/ucarsten-l-96x96.jpg","url":"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/ucarsten-l-96x96.jpg","contentUrl":"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/ucarsten-l-96x96.jpg","caption":"Ulrich Carsten"},"description":"Zertifizierter Bettenfachberater mit dem Schwerpunkt Matratzen in unserem Online-Shop Betten.de und seit 2011 Chef-Redakteur im Betten.de-Schlafmagazin.","url":"https:\/\/www.betten.de\/magazin\/author\/admin"}]}},"lang":"de-at","translations":{"de-at":34279,"de-de":621},"pll_sync_post":{},"_links":{"self":[{"href":"https:\/\/www.betten.at\/magazin\/wp-json\/wp\/v2\/posts\/34279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.betten.at\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.betten.at\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.betten.at\/magazin\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.betten.at\/magazin\/wp-json\/wp\/v2\/comments?post=34279"}],"version-history":[{"count":0,"href":"https:\/\/www.betten.at\/magazin\/wp-json\/wp\/v2\/posts\/34279\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.betten.at\/magazin\/wp-json\/wp\/v2\/media\/46323"}],"wp:attachment":[{"href":"https:\/\/www.betten.at\/magazin\/wp-json\/wp\/v2\/media?parent=34279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.betten.at\/magazin\/wp-json\/wp\/v2\/categories?post=34279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.betten.at\/magazin\/wp-json\/wp\/v2\/tags?post=34279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}